{"id":93655,"date":"2021-07-19T23:59:39","date_gmt":"2021-07-20T02:59:39","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=93655"},"modified":"2021-07-21T08:23:29","modified_gmt":"2021-07-21T11:23:29","slug":"ferro-y-argentino-son-lideres-despues-del-reinicio-del-futbol-alvearense","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/ferro-y-argentino-son-lideres-despues-del-reinicio-del-futbol-alvearense\/","title":{"rendered":"FERRO Y ARGENTINO SON L\u00cdDERES DESPU\u00c9S DEL REINICIO DEL F\u00daTBOL ALVEARENSE"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong>En la vuelta del f\u00fatbol local, Ferro empat\u00f3 con Col\u00f3n y sigue siendo l\u00edder junto con Argentino, que qued\u00f3 libre. Adem\u00e1s, ganaron Bowen, Pac\u00edfico y 10 de Septiembre, que acortaron diferencias con los l\u00edderes.<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">Este domingo en Alvear Oeste, <strong>Ferro sostuvo la punta en un duro partido ante Col\u00f3n, que termin\u00f3 en empate 1 a 1.<\/strong> El <strong>primero vino de Francisco Cruz<\/strong> en un mano a mano ante Dante Barroso al final de la primera mitad, para el visitante que fue superior en ese tramo.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el complemento, y especialmente en los \u00faltimos minutos de partido, el tr\u00e1mite cambi\u00f3 rotundamente y <strong>con un zurdazo al segundo palo en una subida de Edgardo Manzano, a los 44&#8242; de la segunda mitad, el lateral sentenci\u00f3 el 1 a 1.<\/strong> Con este resultado, y <strong>teniendo en cuenta los tres puntos de Argentino en su fecha libre, el Verde y la Academia son l\u00edderes del torneo.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Un punto por detr\u00e1s en la tabla qued\u00f3 Bowen, que con gol de Franco Gonz\u00e1lez a los 36&#8242; de la segunda mitad, super\u00f3 por la m\u00ednima a Andes.<\/strong> Adem\u00e1s, en un partido con mucho roce y algunos intercambios verbales, <strong>los dos terminaron con diez jugadores por las expulsiones de Juani Mart\u00ednez, por el lado del Croto a los 27&#8242; del segundo tiempo, y Lautaro Fern\u00e1ndez,<\/strong> a los 38 en el local.<\/span><\/p>\n<p><span style=\"color: #000000;\">Bajando un escal\u00f3n m\u00e1s en la tabla, <strong>Pac\u00edfico tambi\u00e9n se acerc\u00f3 a lo m\u00e1s alto ya que super\u00f3 por la m\u00ednima a Uni\u00f3n de San Luis<\/strong>. Miguel <strong>&#8216;Bacho&#8217; Ros\u00f3n abri\u00f3 el marcador para el local, Alejandro Funes empat\u00f3 en la segunda parte, y Nicol\u00e1s Arce en el \u00faltimo suspiro puso el 2 a 1<\/strong> decisivo para que el Lobo se quede con los tres puntos.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Otro de los ganadores de la fecha fue 10 de Septiembre, ya que gole\u00f3 por 4 a 1 a Circunvalaci\u00f3n con goles de Ramiro Jofr\u00e9, Marcelo S\u00e1nchez en dos oportunidades y Ramiro Calder\u00f3n<\/strong>. <strong>El descuento para la visita fue de Leonel Romero<\/strong>, y si bien el Deportivo tuvo la posibilidad de conseguir otro resultado, <strong>Renzo Rizzi salv\u00f3 al local, con dos penales atajados.<\/strong><\/span><\/p>\n<h4><span style=\"color: #000000;\"><strong>As\u00ed est\u00e1 la tabla de posiciones hasta el momento:<\/strong><\/span><\/h4>\n<ol>\n<li><span style=\"color: #000000;\"><strong>Argentino 19 pts.<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Ferro 19<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Bowen 18<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Pac\u00edfico 17<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Andes 13<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Col\u00f3n 10<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>10 de Septiembre 10<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Uni\u00f3n 7<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Circunvalaci\u00f3n 3<\/strong><\/span><\/li>\n<\/ol>\n<h5><span style=\"color: #000000;\">\u2022<strong>Lucas Arenas.<\/strong><\/span><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>En la vuelta del f\u00fatbol local, Ferro empat\u00f3 con Col\u00f3n y sigue siendo l\u00edder junto con Argentino, que qued\u00f3 libre. Adem\u00e1s, &#8230;<\/p>\n","protected":false},"author":7,"featured_media":93656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,3],"tags":[],"class_list":["post-93655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-deportes"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/93655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=93655"}],"version-history":[{"count":7,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/93655\/revisions"}],"predecessor-version":[{"id":93837,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/93655\/revisions\/93837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/93656"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=93655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=93655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=93655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}