{"id":80767,"date":"2020-11-18T09:36:23","date_gmt":"2020-11-18T12:36:23","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=80767"},"modified":"2020-11-18T14:03:38","modified_gmt":"2020-11-18T17:03:38","slug":"fallecio-julio-chichino-di-paolo-un-alvearense-de-buena-madera","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/fallecio-julio-chichino-di-paolo-un-alvearense-de-buena-madera\/","title":{"rendered":"FALLECIO JULIO \u201cCHICHINO\u201d DI PAOLO: UN ALVEARENSE DE BUENA MADERA"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong>A la edad de 90 a\u00f1os, dej\u00f3 de existir el Sr. Julio \u201cChichino\u201d Di Paolo, un reconocido empresario alvearense e icono del rubro maderero en nuestro departamento. Sus restos ser\u00e1n sepultados en el cementerio local a las 11 horas.<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">Durante la jornada, <strong>las puertas de Di Paolo Maderas permanecer\u00e1n cerradas,<\/strong> en honor al duelo familiar y al acompa\u00f1amiento de todos los seres queridos.<\/span><\/p>\n<hr \/>\n<p><span style=\"color: #000000;\">Julio <strong>hab\u00eda nacido un 13 de agosto de 1930 en General Alvear<\/strong>, hijo de Julio Di Paolo y Carmen Franco.<\/span><\/p>\n<p><span style=\"color: #000000;\">Su infancia estuvo marcada por un entorno familiar abocado a la producci\u00f3n agr\u00edcola. Recibi\u00f3 su educaci\u00f3n primaria en el colegio Carlos Mar\u00eda de Alvear, siendo por aquel tiempo uno de los primeros alumnos que concurrieron a dicho establecimiento.<\/span><\/p>\n<p><span style=\"color: #000000;\">De esta manera una vez terminado el proceso de educaci\u00f3n, a partir del a\u00f1o 1948, comienza a gestarse la idea de crear un aserradero, de esta manera nace su empresa Di Paolo Maderas, en una sociedad netamente familiar. La cual fueron forjando desde los cimientos hasta llegar a la gran empresa maderera que hoy se encuentra en el Departamento. Al principio trabajaron en familia, no contaban con veh\u00edculos, empleados, pero todos colaboraban en el emprendimiento.<\/span><\/p>\n<p><span style=\"color: #000000;\">Durante el a\u00f1o 1955 lograron darle forma a Di Paolo Maderas y en el a\u00f1o 1962 se posicionaron como una de las m\u00e1s importantes asociaciones del Departamento en lo que se refiere a industria maderera.<\/span><\/p>\n<p><span style=\"color: #000000;\">A lo largo de los a\u00f1os la empresa continu\u00f3 creciendo, se abri\u00f3 el negocio de muebler\u00eda, bodegas, se dividieron, pero, \u201cChichino\u201d, siempre \u00e9l se mantuvo en el rubro de la madera. En la actualidad la compa\u00f1\u00eda se ha extendido a trav\u00e9s de la exportaci\u00f3n de productos hacia numerosos rincones del pa\u00eds.<\/span><\/p>\n<h5><span style=\"color: #000000;\"><strong><em>A.C.<\/em><\/strong><\/span><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A la edad de 90 a\u00f1os, dej\u00f3 de existir el Sr. Julio \u201cChichino\u201d Di Paolo, un reconocido empresario alvearense e icono &#8230;<\/p>\n","protected":false},"author":7,"featured_media":80769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11],"tags":[],"class_list":["post-80767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-sociales"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=80767"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80767\/revisions"}],"predecessor-version":[{"id":80772,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80767\/revisions\/80772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/80769"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=80767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=80767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=80767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}