{"id":80664,"date":"2020-11-17T10:20:11","date_gmt":"2020-11-17T13:20:11","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=80664"},"modified":"2020-11-18T07:47:56","modified_gmt":"2020-11-18T10:47:56","slug":"buscan-que-los-alvearenses-determinen-nuevas-alternativas-de-horarios-en-la-atencion-comercial","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/buscan-que-los-alvearenses-determinen-nuevas-alternativas-de-horarios-en-la-atencion-comercial\/","title":{"rendered":"BUSCAN QUE LOS ALVEARENSES DETERMINEN NUEVAS ALTERNATIVAS DE HORARIOS EN LA ATENCI\u00d3N COMERCIAL"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong>A trav\u00e9s de un proyecto de resoluci\u00f3n, el Concejal Daniel L\u00f3pez (Pro) busca convocar a encuesta p\u00fablica para conocer la opini\u00f3n de los alvearenses, sobre las nuevas alternativas de horarios que surgen en la atenci\u00f3n de:<\/strong><\/span><\/h4>\n<ul>\n<li><span style=\"color: #000000;\"><strong>Supermercados.<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Mayoristas y Distribuidoras.<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Entidades Financieras. <\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Obras Sociales y Mutuales.<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Aseguradoras.<\/strong><\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Cadenas Comerciales de Venta de<\/strong> <strong>Electrodom\u00e9sticos y grandes firmas.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">El proyecto tiene por objetivo, en el marco de una \u201c<strong><em>nueva normalidad<\/em><\/strong>\u201d, buscar la opini\u00f3n y postura de la sociedad, en especial de Comerciantes y Empleados. Ya que a ra\u00edz de la pandemia de COVID-19, esta posibilidad vuelve a surgir, pero esta vez como una alternativa para sumar innumerables beneficios para la poblaci\u00f3n en general.<\/span><\/p>\n<p><span style=\"color: #000000;\">En di\u00e1logo con <strong>F.M. Vi\u00f1as<\/strong>, el edil explic\u00f3: \u00ab<strong><em>En este marco queremos tener un panorama de c\u00f3mo el vecino y el comerciante se ha adaptado a las distintas modalidades. Desde el HCD nos propusimos llevar adelante una encuesta v\u00eda redes sociales para obtener la opini\u00f3n en este sentido<\/em><\/strong>\u00ab.<\/span><\/p>\n<p><span style=\"color: #000000;\">Se est\u00e1n buscando herramientas que ordenen y garanticen, m\u00e1s que nunca, una mejor calidad de vida para cada habitante, y muchas veces esto implica cambios de h\u00e1bitos: \u00ab<strong><em>La idea es con base en los resultados obtenidos avanzar en una nueva normalidad que pretende que el horario de atenci\u00f3n sea de corrido y si esto beneficia a los empleados y comerciantes mejorando su calidad de vida o si tenemos que pensar en volver a la vieja normalidad\u00bb<\/em><\/strong>, subray\u00f3 L\u00f3pez.<\/span><\/p>\n<p><span style=\"color: #000000;\">El sondeo se realiza <strong>a trav\u00e9s de las redes sociales del Concejo Deliberante<\/strong> \u00ab<strong><em>con muy buena devoluci\u00f3n de la gente con resultados sorprendentes. Hay para hacer muchos an\u00e1lisis que nos llevan a una etapa de reinventarnos en todo el sector comercia<\/em><em>l. No es vinculante en una ordenanza que lleve a determinar el horario de corrido, sino que al momento es solo un relevamiento<\/em><\/strong>\u00ab, evalu\u00f3 el concejal del Pro.<\/span><\/p>\n<p><span style=\"color: #000000;\">Est\u00e1 comprobado que las ciudades que ya implementan el horario de corrido en comercios, apuntan a una menor movilidad de los empleados de comercios, a un ahorro de energ\u00eda y a menos hechos de inseguridad, ya que la gente ingresar\u00eda a trabajar de d\u00eda y regresar\u00eda a su casa tambi\u00e9n con luz natural. Tambi\u00e9n <strong>afectar\u00eda favorablemente a la poblaci\u00f3n en cuanto a su bienestar f\u00edsico, emocional y familiar<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al ser consultado sobre la tendencia en la encuesta, <strong>Daniel L\u00f3pez<\/strong> asever\u00f3 que \u00ab<strong><em>el relevamiento durar\u00e1 hasta fin de a\u00f1o y los primeros d\u00edas de marzo se tendr\u00e1 un resultado concreto. Hay un importante porcentaje de opiniones que ven con buenos ojos en que Alvear se aboque al horario de corrido<\/em><\/strong>\u00ab.<\/span><\/p>\n<h5><span style=\"color: #000000;\">\u2022Fernando Burett (F.M. Vi\u00f1as).<\/span><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un proyecto de resoluci\u00f3n, el Concejal Daniel L\u00f3pez (Pro) busca convocar a encuesta p\u00fablica para conocer la opini\u00f3n &#8230;<\/p>\n","protected":false},"author":8,"featured_media":80665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,26],"tags":[],"class_list":["post-80664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-hcd"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=80664"}],"version-history":[{"count":4,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80664\/revisions"}],"predecessor-version":[{"id":80718,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/80664\/revisions\/80718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/80665"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=80664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=80664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=80664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}