{"id":162429,"date":"2026-07-15T10:48:14","date_gmt":"2026-07-15T13:48:14","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=162429"},"modified":"2026-07-15T10:48:14","modified_gmt":"2026-07-15T13:48:14","slug":"internados-a-mas-de-100-km-en-el-desierto-los-operarios-de-vialidad-avanzan-con-las-rutas-ganaderas","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/internados-a-mas-de-100-km-en-el-desierto-los-operarios-de-vialidad-avanzan-con-las-rutas-ganaderas\/","title":{"rendered":"INTERNADOS A M\u00c1S DE 100 KM EN EL DESIERTO, LOS OPERARIOS DE VIALIDAD AVANZAN CON LAS RUTAS GANADERAS"},"content":{"rendered":"<h4 class=\"wp-block-heading\">La Direcci\u00f3n Provincial de Vialidad trabaja en la recuperaci\u00f3n de la Ruta Provincial 152, de Cochic\u00f3, que atraviesa el sur de General Alvear de oeste a este.<\/h4>\n<p><a href=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-162431\" src=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00-768x1024.jpeg 768w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00-225x300.jpeg 225w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00-1152x1536.jpeg 1152w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-00.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p>En las remotas rutas provinciales ubicadas al sur de General Alvear, cerca del l\u00edmite con\u00a0La Pampa, Vialidad Mendoza contin\u00faa avanzando con el mejoramiento y conservaci\u00f3n de los caminos ganaderos, donde se desarrolla una de las actividades de mejor presente econ\u00f3mico por estos d\u00edas, por los altos precios del ganado vacuno en pie.<\/p>\n<p><a href=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-162434\" src=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03-771x1024.jpeg\" alt=\"\" width=\"771\" height=\"1024\" srcset=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03-771x1024.jpeg 771w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03-226x300.jpeg 226w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03-768x1021.jpeg 768w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-03.jpeg 903w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><\/p>\n<p>Habi\u00e9ndose internado m\u00e1s de un centenar de kil\u00f3metros, en lo profundo del desierto, los hombres de la Direcci\u00f3n Provincial de Vialidad, con maquinaria, camiones y casillas para pasar la noche en los lugares de intervenci\u00f3n, trabajan en la recuperaci\u00f3n de la Ruta Provincial 152, tambi\u00e9n conocida como la ruta de Cochic\u00f3, que se extiende por 70 kil\u00f3metros, desde la Ruta Nacional 143 hasta el r\u00edo Desaguadero, en el l\u00edmite con San Luis.<\/p>\n<p>Las tareas se concentran en reparar el camino con el aporte de \u00e1ridos, perfilando, emparejando y compactando luego con maquinaria pesada los puntos cr\u00edticos, por ser medanosos o de descarga de agua cuando hay tormentas, por donde no logran pasar los camiones jaula con ganado bovino.<\/p>\n<p><a href=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-162433\" src=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02-771x1024.jpeg\" alt=\"\" width=\"771\" height=\"1024\" srcset=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02-771x1024.jpeg 771w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02-226x300.jpeg 226w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02-768x1021.jpeg 768w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-02.jpeg 903w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><\/p>\n<p>La importancia de la RP 152 radica adem\u00e1s en que se conecta con otras dos rutas ganaderas, la RP 151, que recientemente Vialidad Mendoza finaliz\u00f3 y que llega hasta la Ruta Nacional 188 (a m\u00e1s de 90 km) que ingresa a la ciudad de General Alvear, y la RP 207, otra ganadera a\u00fan m\u00e1s extensa que tambi\u00e9n corre de norte a sur..<\/p>\n<p>Todas estas rutas recorren campos de miles de hect\u00e1reas, donde los productores ganaderos de zonas \u00e1ridas pastorean y cr\u00edan su ganado vacuno, el cual debe ser trasladado en grandes camiones a trav\u00e9s del desierto hasta las ferias y puntos de venta para su comercializaci\u00f3n.<\/p>\n<p><a href=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-01.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-162432\" src=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-01-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-01-768x1024.jpeg 768w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-01-225x300.jpeg 225w, https:\/\/vinasfm.com\/noticias\/wp-content\/uploads\/2026\/07\/Vialidad-01.jpeg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p>Sin estas remotas rutas transitables los productores no podr\u00edan sacar su ganado del campo para comercializarlo y la actividad se tornar\u00eda imposible de realizar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Provincial de Vialidad trabaja en la recuperaci\u00f3n de la Ruta Provincial 152, de Cochic\u00f3, que atraviesa el sur de &#8230;<\/p>\n","protected":false},"author":7,"featured_media":162435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-162429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fmvinas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=162429"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162429\/revisions"}],"predecessor-version":[{"id":162436,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162429\/revisions\/162436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/162435"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=162429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=162429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=162429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}