{"id":162380,"date":"2026-07-14T11:33:27","date_gmt":"2026-07-14T14:33:27","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=162380"},"modified":"2026-07-15T09:29:53","modified_gmt":"2026-07-15T12:29:53","slug":"historico-fallo-por-maltrato-animal-condenaron-a-dos-personas-por-el-crimen-del-caballo-petiso","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/historico-fallo-por-maltrato-animal-condenaron-a-dos-personas-por-el-crimen-del-caballo-petiso\/","title":{"rendered":"HIST\u00d3RICO FALLO POR MALTRATO ANIMAL: CONDENARON A DOS PERSONAS POR EL CRIMEN DEL CABALLO \u00abPETISO\u00bb"},"content":{"rendered":"<h4><strong>La Justicia de la Segunda Circunscripci\u00f3n Judicial de Mendoza dict\u00f3 una sentencia considerada hist\u00f3rica en materia de derecho animal al condenar a dos personas por el robo, muerte y faenamiento del caballo Petizo, un hecho ocurrido en Bowen que gener\u00f3 una profunda conmoci\u00f3n en la comunidad.<\/strong><\/h4>\n<p>el abogado querellante de la ONG PEMPA, Jer\u00f3nimo Allende, destac\u00f3 el alcance del fallo y asegur\u00f3 que marca un precedente para futuras causas en el sur provincial.<\/p>\n<p><em><strong>\u00abEs hist\u00f3rico porque no lo hab\u00edamos logrado anteriormente en el sur provincial\u00bb, afirm\u00f3 el letrado, quien acompa\u00f1\u00f3 a la familia del animal durante todo el proceso judicial. \u00abNadie va a devolver la vida de Petizo y el dolor de su familia, pero esta sentencia sienta bases para lo que viene\u00bb<\/strong><\/em>, agreg\u00f3.<\/p>\n<p>Allende explic\u00f3 que Petizo no era solamente un caballo para sus due\u00f1os, sino un integrante m\u00e1s de la familia. En particular, manten\u00eda un fuerte v\u00ednculo con Lorena, una adolescente de 14 a\u00f1os, con quien compart\u00eda actividades cotidianas y formaba parte de su proceso de rehabilitaci\u00f3n.<\/p>\n<p><em><strong>\u00abEn este caso, Petizo era parte de la familia, era un miembro m\u00e1s\u00bb<\/strong><\/em>, se\u00f1al\u00f3 el abogado. Adem\u00e1s, record\u00f3 que el equino desapareci\u00f3 a fines de mayo y que, tras una intensa investigaci\u00f3n, un allanamiento permiti\u00f3 encontrar sus restos junto con elementos que permitieron confirmar su identidad, entre ellos el bozal y la cadena identificatoria.<\/p>\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n avanz\u00f3 con la participaci\u00f3n de la Fiscal\u00eda y la querella, que reuni\u00f3 testimonios y distintas pruebas. Seg\u00fan Allende,\u00a0<em><strong>\u00ablas pruebas eran tan contundentes que se dict\u00f3 esta sentencia, esta condena hist\u00f3rica\u00bb<\/strong><\/em>.<\/p>\n<p class=\"wp-block-paragraph\">El fallo conden\u00f3 a dos personas por el delito de abigeato en concurso real con crueldad animal, una figura que, seg\u00fan explic\u00f3 el abogado, representa un avance respecto de resoluciones anteriores, donde generalmente solo se juzgaba el robo de ganado.<\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00abAnteriormente quiz\u00e1s solo se condenaba por abigeato; el sufrimiento que sufri\u00f3 Petizo qued\u00f3 manifestado en la audiencia\u00bb<\/strong><\/em>, sostuvo.<\/p>\n<p class=\"wp-block-paragraph\">Adem\u00e1s, existe una tercera persona que contin\u00faa siendo investigada por presunto encubrimiento y cuya situaci\u00f3n procesal todav\u00eda no fue resuelta.<\/p>\n<p class=\"wp-block-paragraph\">Si bien las penas son de ejecuci\u00f3n condicional, la sentencia establece estrictas reglas de conducta para los condenados durante tres a\u00f1os. Entre ellas se encuentran la prohibici\u00f3n de cometer nuevos delitos, restricciones de acercamiento a la familia damnificada y la inhabilitaci\u00f3n para mantener cualquier tipo de contacto con equinos durante ese per\u00edodo.<\/p>\n<p class=\"wp-block-paragraph\">Tambi\u00e9n deber\u00e1n afrontar una reparaci\u00f3n econ\u00f3mica de car\u00e1cter simb\u00f3lico. <em><strong>\u00abNadie va a devolver la vida de Petizo, pero existe una reparaci\u00f3n simb\u00f3lica y econ\u00f3mica\u00bb<\/strong><\/em>, expres\u00f3 Allende.<\/p>\n<p class=\"wp-block-paragraph\">El abogado explic\u00f3 adem\u00e1s que, si durante el plazo de cumplimiento de las reglas de conducta alguno de los condenados incurre en un nuevo delito o incumple las condiciones impuestas por la Justicia, la condena condicional podr\u00e1 ser revocada y transformarse en una pena de cumplimiento efectivo.<\/p>\n<p class=\"wp-block-paragraph\">Para la querella y la ONG PEMPA, el fallo constituye un paso importante en el reconocimiento de los animales como seres sintientes y en la consolidaci\u00f3n de una jurisprudencia que contemple no solo el da\u00f1o patrimonial, sino tambi\u00e9n el sufrimiento causado a los animales v\u00edctimas de hechos de crueldad.<\/p>\n<h6><strong><span style=\"color: #ff0000;\">Fuente: Diario San Rafael<\/span><\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La Justicia de la Segunda Circunscripci\u00f3n Judicial de Mendoza dict\u00f3 una sentencia considerada hist\u00f3rica en materia de derecho animal al condenar &#8230;<\/p>\n","protected":false},"author":7,"featured_media":162382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-162380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=162380"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162380\/revisions"}],"predecessor-version":[{"id":162381,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162380\/revisions\/162381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/162382"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=162380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=162380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=162380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}