{"id":162186,"date":"2026-07-09T09:09:24","date_gmt":"2026-07-09T12:09:24","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=162186"},"modified":"2026-07-09T21:03:36","modified_gmt":"2026-07-10T00:03:36","slug":"las-lenas-abrira-tres-pistas-de-esqui-gracias-a-la-nieve-artificial","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/las-lenas-abrira-tres-pistas-de-esqui-gracias-a-la-nieve-artificial\/","title":{"rendered":"LAS LE\u00d1AS ABRIR\u00c1 TRES PISTAS DE ESQU\u00cd GRACIAS A LA NIEVE ARTIFICIAL"},"content":{"rendered":"<h4 data-start=\"85\" data-end=\"336\"><strong>A pesar de que la temporada invernal comenz\u00f3 con escasas nevadas en la Cordillera de los Andes, el complejo tur\u00edstico Las Le\u00f1as confirm\u00f3 que este s\u00e1bado 11 de julio habilitar\u00e1 tres pistas de esqu\u00ed gracias al trabajo realizado con nieve artificial.<\/strong><\/h4>\n<p>Asi lo informaba en di\u00e1logo con <strong><span style=\"color: #800080;\">FM VI\u00d1AS<\/span><\/strong> el gerente de actividades de Las Le\u00f1as <strong><span style=\"color: #800080;\">Fernando Passano<\/span><\/strong>: <em><strong>&#8216;desde hace varias semanas el centro ya se encontraba ofreciendo actividades recreativas aunque sin la pr\u00e1ctica del esqu\u00ed&#8217;<\/strong><\/em>, coment\u00f3 <strong><span style=\"color: #800080;\">Fernando<\/span><\/strong> destacando las actividades como el <span style=\"color: #800080;\"><strong data-start=\"488\" data-end=\"507\">Parque Aventura<\/strong><\/span>, donde los visitantes pueden disfrutar de juegos con trineos sobre nieve artificial y el paseo en <strong><span style=\"color: #800080;\">telecabina para peatones<\/span><\/strong>, que permite ascender hasta la media monta\u00f1a y regresar.<\/p>\n<p data-start=\"694\" data-end=\"906\">Adem\u00e1s explic\u00f3 que las <strong><span style=\"color: #800080;\">bajas temperaturas<\/span><\/strong> y la <strong><span style=\"color: #800080;\">incorporaci\u00f3n<\/span><\/strong> de un importante sistema de fabricaci\u00f3n de nieve permitieron acondicionar parte de la monta\u00f1a para dar inicio a la actividad de esqu\u00ed: <strong><em>&#8216;<\/em>apartir del s\u00e1bado quedar\u00e1n habilitadas las pistas Eros Uno, Venus y Neptuno<\/strong>, <em><strong>mientras el complejo permanece a la espera de nuevas nevadas&#8217;<\/strong><\/em>, agreg\u00f3.<\/p>\n<p data-start=\"1120\" data-end=\"1392\">En cuanto al pron\u00f3stico, indic\u00f3 que existe una posibilidad de inestabilidad desde este viernes: <em><strong>&#8216;las previsiones meteorol\u00f3gicas han sido cambiantes en las \u00faltimas semanas, de concretarse las nevadas, podr\u00edan habilitarse m\u00e1s pistas en los pr\u00f3ximos d\u00edas&#8217;<\/strong><\/em>, coment\u00f3.<\/p>\n<p data-start=\"1394\" data-end=\"1624\">Respecto al <strong><span style=\"color: #800080;\">funcionamiento del centro<\/span><\/strong>, se\u00f1al\u00f3 que actualmente el <strong><span style=\"color: #800080;\">personal trabaja en las \u00e1reas que ya est\u00e1n operativas<\/span><\/strong> y que, con la apertura de las pistas, se incorporar\u00e1n nuevos empleados para reforzar la atenci\u00f3n al p\u00fablico.<\/p>\n<p data-start=\"1626\" data-end=\"1975\">En materia de infraestructura, una de las principales novedades de esta temporada es la adquisici\u00f3n de <strong data-start=\"1729\" data-end=\"1776\">11 nuevos ca\u00f1ones para fabricaci\u00f3n de nieve<\/strong>, lo que eleva a <strong data-start=\"1793\" data-end=\"1832\">51 ca\u00f1ones terrestres y tres a\u00e9reos<\/strong> la capacidad del complejo para producir nieve artificial. Adem\u00e1s, se realizaron las tareas habituales de mantenimiento en hoteles y edificios.<\/p>\n<p data-start=\"1977\" data-end=\"2272\">Sobre el acceso al centro de esqu\u00ed, inform\u00f3 que las rutas se encuentran en buenas condiciones y que existe un trabajo coordinado con la Direcci\u00f3n Provincial de Vialidad y la Polic\u00eda para controlar la portaci\u00f3n obligatoria de cadenas y realizar, si fuera necesario, tareas de despeje de nieve.<\/p>\n<p data-start=\"2274\" data-end=\"2604\" data-is-last-node=\"\" data-is-only-node=\"\">\n","protected":false},"excerpt":{"rendered":"<p>A pesar de que la temporada invernal comenz\u00f3 con escasas nevadas en la Cordillera de los Andes, el complejo tur\u00edstico Las &#8230;<\/p>\n","protected":false},"author":7,"featured_media":138582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-162186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=162186"}],"version-history":[{"count":3,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162186\/revisions"}],"predecessor-version":[{"id":162191,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/162186\/revisions\/162191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/138582"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=162186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=162186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=162186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}