{"id":160274,"date":"2026-05-11T09:53:52","date_gmt":"2026-05-11T12:53:52","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=160274"},"modified":"2026-05-13T08:54:41","modified_gmt":"2026-05-13T11:54:41","slug":"millonaria-demanda-al-estado-por-un-hincha-que-perdio-un-ojo-en-un-partido-de-futbol","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/millonaria-demanda-al-estado-por-un-hincha-que-perdio-un-ojo-en-un-partido-de-futbol\/","title":{"rendered":"MILLONARIA DEMANDA AL ESTADO POR UN HINCHA QUE PERDI\u00d3 UN OJO EN UN PARTIDO DE F\u00daTBOL"},"content":{"rendered":"<h4><strong>Tras un juicio civil, el Estado fue condenado por un hincha que perdi\u00f3 un ojo durante los incidentes en un partido de f\u00fatbol en General Alvear.<\/strong><\/h4>\n<p>La justicia civil conden\u00f3 este viernes al estado provincial para que indemnice a un hombre de General Alvear que perdi\u00f3 la visi\u00f3n de un ojo al recibir un balazo durante una represi\u00f3n policial, en medio de los incidentes al t\u00e9rmino de un partido entre Pac\u00edfico y Bowen.<\/p>\n<p>El hecho ocurri\u00f3 en noviembre del 2018 en General Alvear y la justicia logr\u00f3 identificar a los dos efectivos de la Polic\u00eda de Mendoza que fueron autores de la agresi\u00f3n. Por ende, el Gobierno de Mendoza deber\u00e1 responder en forma recurrente.<\/p>\n<p>De esta forma, el Tercer Juzgado Civil orden\u00f3 una indemnizaci\u00f3n de m\u00e1s de $165 millones para el damnificado, un hincha del club Pac\u00edfico. En el mismo fallo, se rechaz\u00f3 la demanda a la Liga Alvearense de F\u00fatbol.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Juicio civil en General Alvear: millonaria demanda al Estado provincial<\/span><\/strong><\/p>\n<p>Seg\u00fan consta en la demanda, todo ocurri\u00f3 el 4 de noviembre del 2018 en el estadio del club Uni\u00f3n Social y Deportivo Bowen, ubicado en el distrito del mismo nombre, en General Alvear.<\/p>\n<p>La v\u00edctima, de quien se reserva su identidad, fue con sus amigos, todos hinchas del Sport Club Pacifico, a presenciar el partido correspondiente al torneo de la Liga Alvearense de F\u00fatbol.<\/p>\n<p>Lo cierto es que tras el partido, el actor sali\u00f3 del estadio y abord\u00f3 el cami\u00f3n que los llevaba de regreso a la ciudad de General Alvear. Sin embargo, a unos 60 metros fueron abordados por polic\u00edas de la Unidad Motorizada de Acci\u00f3n R\u00e1pida, quienes comenzaron a disparar balazos de goma, seg\u00fan la denuncia, sin motivo alguno.<\/p>\n<p>El damnificado recibi\u00f3 un primer disparo en el brazo derecho, y luego, como consecuencia de otro tiro, uno de los perdigones impact\u00f3 en el centro del ojo izquierdo.<\/p>\n<p>A partir de ese instante, el hombre perdi\u00f3 la visibilidad y luego las pericias m\u00e9dicas lo confirmaron.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Los fundamentos del fallo tras el juicio civil<\/span><\/strong><\/p>\n<p>Para los jueces intervinientes, \u201clos agentes obraron de manera irregular\u201d. En los fundamentos de la sentencia explicaron su error \u201cen la medida en que avanzaron hacia los particulares que se encontraban en la parte trasera del cami\u00f3n, sin que se haya acreditado en ellos provocaci\u00f3n o disturbio de ninguna clase, ni agresividad manifiesta hacia el personal policial\u201d.<\/p>\n<p>A su vez, sostuvieron que \u201cLa Liga Alvearense de F\u00fatbol es una entidad sin fines de lucro que no tiene un beneficio econ\u00f3mico que justifique hacerla responsable en forma solidaria como organizadora del evento deportivo\u201d.<\/p>\n<p>En base a esto, ordenaron una indemnizaci\u00f3n de m\u00e1s de $146 millones, condenando a los dos efectivos y al Gobierno de la Provincia de Mendoza, quienes adem\u00e1s deber\u00e1n hacerse cargo de las costas del proceso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras un juicio civil, el Estado fue condenado por un hincha que perdi\u00f3 un ojo durante los incidentes en un partido &#8230;<\/p>\n","protected":false},"author":7,"featured_media":160276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-160274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/160274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=160274"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/160274\/revisions"}],"predecessor-version":[{"id":160275,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/160274\/revisions\/160275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/160276"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=160274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=160274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=160274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}