{"id":154659,"date":"2025-11-05T11:00:23","date_gmt":"2025-11-05T14:00:23","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=154659"},"modified":"2025-11-06T17:09:01","modified_gmt":"2025-11-06T20:09:01","slug":"abren-las-inscripciones-para-quienes-quieran-formar-parte-del-servicio-penitenciario","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/abren-las-inscripciones-para-quienes-quieran-formar-parte-del-servicio-penitenciario\/","title":{"rendered":"ABREN LAS INSCRIPCIONES PARA QUIENES QUIERAN FORMAR PARTE DEL SERVICIO PENITENCIARIO"},"content":{"rendered":"<h4><strong><span style=\"color: #003300;\">Las mismas se realizan de manera virtual ingresando a<\/span> <a href=\"https:\/\/informacionoficial.mendoza.gob.ar\/seguridadyjusticia\/servicio-penitenciario\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd.<\/a> <span style=\"color: #003300;\">Las personas interesadas podr\u00e1n enviar la documentaci\u00f3n solicitada hasta el lunes 2 de febrero del pr\u00f3ximo a\u00f1o.<\/span><\/strong><\/h4>\n<p>El <strong>Servicio Penitenciario de Mendoza<\/strong> da inicio al proceso de inscripci\u00f3n correspondiente a la <strong>Convocatoria de Aspirantes para Agentes del escalaf\u00f3n de Seguridad<\/strong>, cohorte 2026, promoci\u00f3n LXV. La modalidad es por internet, completando un formulario digital, a partir del lunes 10 de noviembre.<\/p>\n<p>Quienes queden seleccionados <strong>podr\u00e1n acceder a una beca mensual, destinada a cubrir gastos de traslado, materiales educativos y otros costos asociados al cursado.<\/strong><\/p>\n<p>Para ello, los postulantes deber\u00e1n subir la documentaci\u00f3n solicitada. La posterior selecci\u00f3n consta de instancias de aptitud f\u00edsica y psicol\u00f3gica, entre otras.\u00a0Una vez terminado este proceso, quienes hayan aprobado las distintas fases comenzar\u00e1n un curso de preparaci\u00f3n de aproximadamente seis meses.<\/p>\n<h2><strong>Documentaci\u00f3n requerida<\/strong><\/h2>\n<p>P\u00e1g. 1 \u2013 DNI frente y reverso<br \/>\nP\u00e1g. 2 \u2013 Constancia de CUIL (<a href=\"http:\/\/www.anses.gob.ar\/consultas\/constancia-de-cuil\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.anses.gob.ar\/consultas\/constancia-de-cuil&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw06iX89VtQ8Ns6wWa6a9Yss\">www.anses.gob.ar\/consultas\/constancia-de-cuil<\/a>)<br \/>\nP\u00e1g.3 \u2013 Partida de Nacimiento actualizada (<a href=\"http:\/\/www.mendoza.gov.ar\/servicios\/gobierno\/partidas-digitales\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.mendoza.gov.ar\/servicios\/gobierno\/partidas-digitales\/&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw2dvcESND4i_KSMElj_hToM\">www.mendoza.gov.ar\/servicios\/gobierno\/partidas-digitales\/<\/a>)<br \/>\nP\u00e1g. 4 \u2013 Certificado Anal\u00edtico de Estudios Secundarios, definitivo y legalizado. (Poder Judicial)<br \/>\nP\u00e1g. 5 \u2013 Certificado de Antecedentes Penales (<a href=\"http:\/\/www.mendoza.gov.ar\/servicios\/gobierno\/certificado-de-antecedentes-penales\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.mendoza.gov.ar\/servicios\/gobierno\/certificado-de-antecedentes-penales\/&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw1mXzz1EAT9zttEkVTB5IXl\">www.mendoza.gov.ar\/servicios\/gobierno\/certificado-de-antecedentes-penales\/<\/a>)<br \/>\nP\u00e1g. 6 \u2013 Certificado m\u00e9dico de aptitud para test f\u00edsico, indicando estatura. M\u00ednimo exigido: 1,55 metros.<br \/>\nP\u00e1g.7 \u2013 Constancia de Junta Electoral (<a href=\"http:\/\/www.argentina.gob.ar\/interior\/observatorioelectoral\/registro-de-infractores\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.argentina.gob.ar\/interior\/observatorioelectoral\/registro-de-infractores&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw1t55xL1QpGU63BGRSRcxAU\">www.argentina.gob.ar\/interior\/observatorioelectoral\/registro-de-infractores<\/a>)<br \/>\nP\u00e1g. 8 \u2013 Constancia Juicios Universales (<a href=\"http:\/\/www.jus.mendoza.gov.ar\/juicios-universales\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.jus.mendoza.gov.ar\/juicios-universales&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw3RH1dccNBxE4Z3BpLd0Q7v\">www.jus.mendoza.gov.ar\/juicios-universales<\/a>)<br \/>\nP\u00e1g. 9 \u2013 Constancia Registro Deudores Alimentarios (<a href=\"http:\/\/www.jus.mendoza.gov.ar\/deudores-alimentarios\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.jus.mendoza.gov.ar\/deudores-alimentarios&amp;source=gmail&amp;ust=1762436328118000&amp;usg=AOvVaw1IT28PcLvKEKH1huZwDjY8\">www.jus.mendoza.gov.ar\/deudores-alimentarios<\/a>)<\/p>\n<p>P\u00e1g. 10 \u2013 Curr\u00edculum Vitae con foto actualizada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mismas se realizan de manera virtual ingresando a AQU\u00cd. Las personas interesadas podr\u00e1n enviar la documentaci\u00f3n solicitada hasta el lunes &#8230;<\/p>\n","protected":false},"author":7,"featured_media":154660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,33],"tags":[],"class_list":["post-154659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-seguridad"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/154659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=154659"}],"version-history":[{"count":3,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/154659\/revisions"}],"predecessor-version":[{"id":154753,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/154659\/revisions\/154753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/154660"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=154659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=154659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=154659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}