{"id":148537,"date":"2025-05-20T10:19:27","date_gmt":"2025-05-20T13:19:27","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=148537"},"modified":"2025-05-21T08:35:48","modified_gmt":"2025-05-21T11:35:48","slug":"habilitaron-un-sitio-web-para-que-sea-mas-facil-tramitar-la-tenencia-de-armas","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/habilitaron-un-sitio-web-para-que-sea-mas-facil-tramitar-la-tenencia-de-armas\/","title":{"rendered":"HABILITARON UN SITIO WEB PARA QUE SEA \u201cM\u00c1S F\u00c1CIL\u201d TRAMITAR LA TENENCIA DE ARMAS"},"content":{"rendered":"<h4><strong><span style=\"color: #003300;\">El nuevo procedimiento est\u00e1 disponible para usuarios individuales y miembros de las Fuerzas Armadas, de Seguridad, policiales y del Servicio Penitenciario.<\/span><\/strong><\/h4>\n<p>En un nuevo paso hacia la transformaci\u00f3n digital, la\u00a0<strong>Agencia Nacional de Materiales Controlados (ANMaC)\u00a0<\/strong>oficializ\u00f3 la creaci\u00f3n de\u00a0<em>\u201cTenencia Express\u201d<\/em>, un tr\u00e1mite digital que permitir\u00e1 a los usuarios gestionar la tenencia de<strong>\u00a0armas de fuego<\/strong>\u00a0de manera r\u00e1pida y completamente\u00a0<strong>online<\/strong>.<\/p>\n<p>La medida, aprobada mediante la Resoluci\u00f3n 45\/2025 y publicada en el Bolet\u00edn Oficial, se implementar\u00e1 a trav\u00e9s de la plataforma\u00a0<strong>\u201cMiAnmac\u201d<\/strong>, desarrollada para agilizar la gesti\u00f3n de tr\u00e1mites relacionados con\u00a0<strong>armas\u00a0<\/strong>y materiales controlados.<\/p>\n<p>El nuevo procedimiento est\u00e1 disponible para\u00a0<strong>usuarios individuales y miembros de las Fuerzas Armadas, de Seguridad, policiales y del Servicio Penitenciario<\/strong>, siempre que adquieran armas con C\u00f3digo \u00danico de Identificaci\u00f3n del Material (CUIM).<\/p>\n<p>Entre las principales mejoras del sistema, se destacan los controles automatizados sobre los antecedentes del solicitante, la validaci\u00f3n en l\u00ednea de su situaci\u00f3n de revista en el caso de pertenecer a alguna fuerza de seguridad, y la\u00a0<strong>integraci\u00f3n de pagos digitales<\/strong>.<\/p>\n<p>Asimismo, el tr\u00e1mite contempla la emisi\u00f3n de credenciales electr\u00f3nicas de tenencia y de la\u00a0<strong>Tarjeta de Consumo de Municiones (TCCM)<\/strong>, que podr\u00e1n visualizarse desde la aplicaci\u00f3n gubernamental\u00a0<strong>\u201cMiArgentina\u201d<\/strong>.<\/p>\n<p>Con esta iniciativa, la ANMaC busca\u00a0<strong>reducir los tiempos de gesti\u00f3n, mejorar la trazabilidad y garantizar mayor transparencia<\/strong>\u00a0en los procesos de control de armas en el pa\u00eds.<\/p>\n<p>El arancel fijado para la tramitaci\u00f3n de \u201cTenencia Express\u201d ser\u00e1 de\u00a0<strong>20 Unidades ANMaC<\/strong>, mientras que la gesti\u00f3n de la\u00a0<strong>TCCM asociada<\/strong>\u00a0tendr\u00e1 un costo de\u00a0<strong>10 Unidades ANMaC<\/strong>.<\/p>\n<p>Desde el organismo, encabezado por su director ejecutivo\u00a0<strong>Juan Pablo Allan<\/strong>, destacaron que esta iniciativa forma parte de un\u00a0<strong>proceso m\u00e1s amplio de modernizaci\u00f3n tecnol\u00f3gica y simplificaci\u00f3n administrativa<\/strong>, en l\u00ednea con la Ley Nacional de Armas y Explosivos N\u00b0 20.429 y sus normas complementarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo procedimiento est\u00e1 disponible para usuarios individuales y miembros de las Fuerzas Armadas, de Seguridad, policiales y del Servicio Penitenciario. &#8230;<\/p>\n","protected":false},"author":7,"featured_media":148538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,33],"tags":[],"class_list":["post-148537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-seguridad"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=148537"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148537\/revisions"}],"predecessor-version":[{"id":148539,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148537\/revisions\/148539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/148538"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=148537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=148537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=148537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}