{"id":148282,"date":"2025-05-14T09:16:50","date_gmt":"2025-05-14T12:16:50","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=148282"},"modified":"2025-05-15T08:28:36","modified_gmt":"2025-05-15T11:28:36","slug":"quieren-reactivar-campos-del-sur-con-una-ley-para-cancelar-hipotecas-viejas","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/quieren-reactivar-campos-del-sur-con-una-ley-para-cancelar-hipotecas-viejas\/","title":{"rendered":"QUIEREN REACTIVAR CAMPOS DEL SUR CON UNA LEY PARA CANCELAR HIPOTECAS VIEJAS"},"content":{"rendered":"<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span style=\"color: #003300;\"><strong>El Gobierno provincial impulsa una ley para cancelar hipotecas hist\u00f3ricas sobre tierras rurales, que impiden la producci\u00f3n en miles de hect\u00e1reas del sur mendocino.<\/strong><\/span><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><em><strong>\u201cHace casi tres d\u00e9cadas, cuando la Provincia asumi\u00f3 la administraci\u00f3n de los cr\u00e9ditos otorgados por los antiguos bancos oficiales, muchos productores no lograron afrontar sus obligaciones. A\u00fan hoy subsisten deudas garantizadas con hipotecas sobre tierras rurales, lo que impide que esas propiedades se pongan a producir\u201d<\/strong><\/em>, explic\u00f3 el<strong><span style=\"color: #003366;\"> gobernador Alfredo Cornejo<\/span><\/strong> sorbe en el mardo de la 44\u00b0 Fiesta Nacional de la Ganader\u00eda de Zonas \u00c1ridas.<\/div>\n<\/div>\n<div dir=\"auto\">\n<p>Este situaci\u00f3n frena directamente el crecimiento productivo de Mendoza, y asegur\u00f3 que<strong> el objetivo de la nueva ley es liberar esas tierras para que puedan volver a generar trabajo y desarrollo<\/strong>. La medida apunta a reincorporar miles de hect\u00e1reas al circuito agr\u00edcola y ganadero.<\/p>\n<div id=\"standard_4\" class=\"st-placement standard_4 inArticle\">\n<div class=\"st-adunit-inarticle st-inarticle-slot\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\">\n<div class=\"st-adunit-ad st-reset\">\n<div class=\"st-display-render st-reset open 300x250\">\n<div class=\"st-canvas st-reset vertical-static\">\n<div class=\"x-to-close st-reset\">\n<p>Uno de los aspectos m\u00e1s destacados del anuncio es que el proceso se har\u00e1 de manera simplificada para facilitar los tr\u00e1mites. En ese sentido, el Gobierno instalar\u00e1 una oficina transitoria de la Direcci\u00f3n de Administraci\u00f3n de Activos de ex Bancos Oficiales (DAABO) en San Rafael, que funcionar\u00e1 dentro del Ministerio de la Producci\u00f3n.<\/p>\n<p><em><strong>\u201cMendoza quiere cumplir con su deber constitucional de promover el desarrollo y el empleo, pero necesitamos que los titulares o herederos impulsen los tr\u00e1mites\u201d<\/strong><\/em>, enfatiz\u00f3 Cornejo, instando a los productores a sumarse al proceso.<\/p>\n<p><span class=\"sigijh_hlt sigijh_animateMe\">La propuesta fue uno de los anuncios m\u00e1s celebrados, especialmente en el sur provincial, donde existen numerosos campos hipotecados que podr\u00edan volver a la actividad con este alivio legal.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno provincial impulsa una ley para cancelar hipotecas hist\u00f3ricas sobre tierras rurales, que impiden la producci\u00f3n en miles de hect\u00e1reas &#8230;<\/p>\n","protected":false},"author":7,"featured_media":148283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,77],"tags":[],"class_list":["post-148282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-gobierno"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=148282"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148282\/revisions"}],"predecessor-version":[{"id":148284,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148282\/revisions\/148284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/148283"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=148282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=148282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=148282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}