{"id":148138,"date":"2025-05-10T09:33:03","date_gmt":"2025-05-10T12:33:03","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=148138"},"modified":"2025-05-12T09:42:14","modified_gmt":"2025-05-12T12:42:14","slug":"concejal-de-guaymallen-dio-positivo-en-alcoholemia-en-alvear-y-le-secuestraron-el-auto","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/concejal-de-guaymallen-dio-positivo-en-alcoholemia-en-alvear-y-le-secuestraron-el-auto\/","title":{"rendered":"CONCEJAL DE GUAYMALL\u00c9N DIO POSITIVO EN ALCOHOLEMIA EN ALVEAR Y LE SECUESTRARON EL AUTO"},"content":{"rendered":"<h4><strong><span style=\"color: #003300;\">El edil de Cambia Mendoza, Miqueas Burgoa, fue detenido en Bowen tras arrojar 1,25 g\/l en un test de alcoholemia. Termin\u00f3 demorado en la comisaria 46 del distrito sure\u00f1o.<\/span><\/strong><\/h4>\n<p>En la madrugada del s\u00e1bado, el concejal de\u00a0<strong>Cambia Mendoza<\/strong>\u00a0por Guaymall\u00e9n,\u00a0<strong>Miqueas Burgoa<\/strong>, dio positivo en un control de<strong>\u00a0alcoholemia<\/strong>\u00a0en\u00a0General Alvear. El edil\u00a0<strong>registr\u00f3 1,25 gramos de alcohol en sangre al momento del dosaje.<\/strong>\u00a0El caso qued\u00f3 en manos de la Justicia Contravencional.<\/p>\n<article class=\"article-body article-body--second-paragraph\">Burgoa, integrante del bloque oficialista departamental, no estaba solo al momento del test: lo acompa\u00f1aba<strong>\u00a0Emiliano Gobbi<\/strong>, asesor legislativo del senador provincial y exintendente de Guaymall\u00e9n,\u00a0<strong>Marcelino Iglesias<\/strong>.<\/p>\n<\/article>\n<article class=\"article-body article-body--third-paragraph\">El hecho ocurri\u00f3 cerca de las 5.20 de la ma\u00f1ana, cuando ambos sal\u00edan de un local bailable ubicado en el distrito de<strong>\u00a0Bowen<\/strong>. Previamente, hab\u00edan participado de la tradicional\u00a0<strong>Paella Radical<\/strong>\u00a0que se realiz\u00f3 en la Ciudad de Alvear.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.losandes.com.ar\/p\/fe0ca5fb1bdb9e7ec515e5e0da33d43c\/adjuntos\/368\/imagenes\/100\/621\/0100621462\/1000x0\/smart\/miquea-burgoajpg.jpg\" alt=\"El concejal de Cambia Mendoza en Guaymall\u00e9n, Miquea Burgoa.\" \/><\/p>\n<article class=\"article-body article-body--fifth-paragraph\">Tras detener el veh\u00edculo, los uniformados realizaron el test de alcoholemia, que dio resultado positivo. Adem\u00e1s, el concejal\u00a0<strong>no contaba con su licencia de conducir f\u00edsica<\/strong>\u00a0ni con bater\u00eda en su celular, por lo que no pudo mostrar el carnet digital a trav\u00e9s de la app Mi Argentina.<\/p>\n<\/article>\n<article class=\"article-body article-body--third-paragraph\">Dado que la infracci\u00f3n incluy\u00f3 conducci\u00f3n con m\u00e1s de un gramo de alcohol en sangre y falta de documentaci\u00f3n, se considera una falta grave. El caso qued\u00f3 a cargo de un juez Contravencional.<\/p>\n<p>Seg\u00fan testigos, cuando la polic\u00eda intent\u00f3 secuestrar el veh\u00edculo, tanto Burgoa como Gobbi reaccionaron de forma violenta y se negaron al procedimiento, por lo que los efectivos solicitaron refuerzos.<\/p>\n<p>\u201c<strong>Dec\u00edan que no pod\u00edan llevarlos a la comisar\u00eda porque eran funcionarios p\u00fablicos del Gran Mendoza<\/strong>\u201d, relat\u00f3 un testigo del hecho.<\/p>\n<p>Una vez que llegaron m\u00e1s m\u00f3viles policiales, ambos fueron detenidos y trasladados a la comisar\u00eda 46 de Bowen, donde permanecieron demorados hasta el mediod\u00eda del s\u00e1bado. El veh\u00edculo, propiedad del concejal, qued\u00f3 secuestrado.<\/p>\n<p>Burgoa podr\u00eda enfrentar una pena\u00a0<strong>de hasta 90 d\u00edas de arresto e inhabilitaci\u00f3n para conducir por un a\u00f1o y medio.<\/strong>\u00a0La Ley 9099, art\u00edculo 67 bis \u2014modificada el a\u00f1o pasado mediante una reforma impulsada por la ministra de Seguridad y Justicia,\u00a0<strong>Mercedes Rus<\/strong>\u2014 tambi\u00e9n contempla\u00a0<strong>multas de hasta m\u00e1s de 4.500.000 pesos<\/strong>.<\/p>\n<\/article>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>El edil de Cambia Mendoza, Miqueas Burgoa, fue detenido en Bowen tras arrojar 1,25 g\/l en un test de alcoholemia. Termin\u00f3 &#8230;<\/p>\n","protected":false},"author":7,"featured_media":148139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,4],"tags":[],"class_list":["post-148138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insolito","category-policiales"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=148138"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148138\/revisions"}],"predecessor-version":[{"id":148155,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/148138\/revisions\/148155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/148139"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=148138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=148138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=148138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}