{"id":147516,"date":"2025-04-29T08:43:44","date_gmt":"2025-04-29T11:43:44","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=147516"},"modified":"2025-04-30T09:03:32","modified_gmt":"2025-04-30T12:03:32","slug":"las-destrezas-criollas-crecieron-significativamente-en-la-fiesta-nacional-de-la-ganaderia","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/las-destrezas-criollas-crecieron-significativamente-en-la-fiesta-nacional-de-la-ganaderia\/","title":{"rendered":"LAS DESTREZAS CRIOLLAS CRECIERON SIGNIFICATIVAMENTE EN LA FIESTA NACIONAL DE LA GANADER\u00cdA"},"content":{"rendered":"<h4 data-start=\"124\" data-end=\"263\"><span style=\"color: #003300;\"><strong>La final del 4\u00b0 Torneo Nacional de Destrezas Criollas se celebrar\u00e1 el pr\u00f3ximo 10 de mayo, dentro del Gran Festival Ecuestre de la 44\u00b0 Fiesta Nacional de la Ganader\u00eda.<\/strong><\/span><\/h4>\n<p class=\"\" data-start=\"265\" data-end=\"575\">En di\u00e1logo con <span style=\"color: #800080;\"><strong>FM VI\u00d1AS<\/strong><\/span>, <strong><span style=\"color: #003366;\">Miguel Sosa<\/span><\/strong>, c<em>oordinador de Destrezas Criollas de la Fiesta Nacional de la Ganader\u00eda<\/em>, brind\u00f3 un panorama completo sobre la organizaci\u00f3n y expectativas de esta actividad que tendr\u00e1 su gran jornada el s\u00e1bado 10 de mayo, consolid\u00e1ndose como uno de los puntos m\u00e1s tradicionales del evento.<\/p>\n<p class=\"\" data-start=\"577\" data-end=\"918\"><strong>\u201cEste a\u00f1o volvemos con todo desde temprano. La jornada iniciar\u00e1 a las 09:00 horas y se extender\u00e1 durante todo el d\u00eda\u201d<\/strong>, explic\u00f3 Sosa. Este a\u00f1o se celebrar\u00e1 la final del <strong data-start=\"747\" data-end=\"791\">4\u00b0 Torneo Nacional de Destrezas Criollas<\/strong>, que lleva el nombre de <strong data-start=\"816\" data-end=\"845\">Domingo \u201cPitulo\u201d Aguilera<\/strong>, en homenaje a uno de los tradicionalistas m\u00e1s reconocidos de la regi\u00f3n.<\/p>\n<p class=\"\" data-start=\"920\" data-end=\"1254\">Sosa detall\u00f3 que el torneo ha crecido significativamente, con una clasificaci\u00f3n que reuni\u00f3 a <strong data-start=\"1013\" data-end=\"1033\">74 participantes<\/strong>, de los cuales <strong data-start=\"1049\" data-end=\"1075\">36 llegaron a la final<\/strong>. En esta edici\u00f3n, la categor\u00eda de menores se redujo a 13 participantes, debido a que muchos j\u00f3venes pasaron a la categor\u00eda mayores y otros, por distintos motivos, no continuaron.<\/p>\n<p class=\"\" data-start=\"1256\" data-end=\"1737\">Los juegos se mantendr\u00e1n igual que en la clasificatoria: los <strong data-start=\"1317\" data-end=\"1373\">menores competir\u00e1n en \u201c8 Simple\u201d y \u201cCriollos de Am\u00e9rica\u201d<\/strong>, mientras que los <strong data-start=\"1392\" data-end=\"1423\">mayores sumar\u00e1n \u201cEl Trebol\u201d<\/strong>. Adem\u00e1s, cada uno de los juegos en la categor\u00eda mayores estar\u00e1 dividido en tres copas \u2014<strong data-start=\"1511\" data-end=\"1534\">Oro, Plata y Bronce<\/strong>\u2014 lo que permitir\u00e1 ampliar la cantidad de premiados y reconocer el esfuerzo de m\u00e1s participantes. <em><strong>\u201cCon esto buscamos compensar el esfuerzo econ\u00f3mico y el compromiso que implica participar\u201d<\/strong><\/em>, expres\u00f3 Sosa.<\/p>\n<p class=\"\" data-start=\"1739\" data-end=\"1995\">Uno de los pilares del reglamento de participaci\u00f3n es el <strong data-start=\"1796\" data-end=\"1855\">buen comportamiento del jinete y el cuidado del caballo<\/strong>, una exigencia que, seg\u00fan Sosa, <strong>algunos encuentran dif\u00edcil, pero que es irrenunciable para mantener el esp\u00edritu y la integridad del evento.<\/strong><\/p>\n<p class=\"\" data-start=\"1997\" data-end=\"2254\">En cuanto al acceso, se inform\u00f3 que habr\u00e1 un <em><strong data-start=\"2042\" data-end=\"2061\">\u201cbono ecuestre\u201d<\/strong><\/em>, que permitir\u00e1 el ingreso al predio tanto s\u00e1bado como domingo, incluyendo la muestra comercial y las actividades de destrezas. La entrada general del s\u00e1bado tendr\u00e1 un costo de <strong data-start=\"2238\" data-end=\"2253\">4.000 pesos<\/strong>.<\/p>\n<p class=\"\" data-start=\"2256\" data-end=\"2513\">El evento tambi\u00e9n contar\u00e1 con animaci\u00f3n a cargo de <span style=\"color: #003366;\"><strong data-start=\"2307\" data-end=\"2325\">Miguel Coronel<\/strong><\/span>, quien ya particip\u00f3 de las clasificatorias, y se eval\u00faa seguir contando con su presencia en la final. <em><strong>\u201cEstamos viendo si lo mejoramos, entren\u00e1ndolo un poquito en estos d\u00edas\u201d<\/strong><\/em>, brome\u00f3 Sosa.<\/p>\n<p class=\"\" data-start=\"2515\" data-end=\"2838\">Por \u00faltimo, destac\u00f3 el <strong data-start=\"2538\" data-end=\"2592\">crecimiento del n\u00famero de centros tradicionalistas<\/strong> y el <strong data-start=\"2598\" data-end=\"2648\">apoyo del municipio y la Direcci\u00f3n de Deportes<\/strong>, que este a\u00f1o extienden la premiaci\u00f3n a todas las categor\u00edas. <em><strong>\u201cEsto es muy importante porque hablamos de una actividad costosa, con gastos que no se detienen durante el a\u00f1o\u201d<\/strong><\/em>, concluy\u00f3 Sosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La final del 4\u00b0 Torneo Nacional de Destrezas Criollas se celebrar\u00e1 el pr\u00f3ximo 10 de mayo, dentro del Gran Festival Ecuestre &#8230;<\/p>\n","protected":false},"author":7,"featured_media":147517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,28],"tags":[],"class_list":["post-147516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-fiesta-nacional-de-la-ganaderia"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/147516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=147516"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/147516\/revisions"}],"predecessor-version":[{"id":147518,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/147516\/revisions\/147518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/147517"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=147516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=147516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=147516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}