{"id":146149,"date":"2025-04-01T09:37:02","date_gmt":"2025-04-01T12:37:02","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=146149"},"modified":"2025-04-01T12:23:49","modified_gmt":"2025-04-01T15:23:49","slug":"delincuentes-robaron-una-gran-cantidad-de-elementos-de-una-obra-en-construccion","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/delincuentes-robaron-una-gran-cantidad-de-elementos-de-una-obra-en-construccion\/","title":{"rendered":"DELINCUENTES ROBARON UNA GRAN CANTIDAD DE ELEMENTOS DE UNA OBRA EN CONSTRUCCI\u00d3N"},"content":{"rendered":"<h4 data-sourcepos=\"5:1-5:247\"><span style=\"color: #000000;\">Un robo de importantes materiales de construcci\u00f3n fue denunciado este lunes en la Comisar\u00eda 14. El hecho ocurri\u00f3 en una obra en construcci\u00f3n ubicada en la calle Roca N\u00b0 9, propiedad de D.A. G.R (44).<\/span><\/h4>\n<p data-sourcepos=\"7:1-7:362\"><span style=\"color: #000000;\">Seg\u00fan la denuncia, <strong>el propietario constat\u00f3 que autores ignorados ingresaron al lugar tras da\u00f1ar la puerta de una habitaci\u00f3n.<\/strong> Los delincuentes sustrajeron una <strong>bomba autocebante para pileta marca Vulcano de color negro, tres rollos de cable de 30 metros cada uno y una cantidad significativa de materiales el\u00e9ctricos, incluyendo conectores, curvas, cajas y ca\u00f1os.<\/strong><\/span><\/p>\n<p data-sourcepos=\"9:1-9:234\"><span style=\"color: #000000;\"><strong>La polic\u00eda se encuentra investigando el hecho para dar con los responsables y recuperar los elementos robados.<\/strong> Se solicita a la comunidad que, en caso de tener informaci\u00f3n relevante, se comunique con al 911 o acuda a la dependencia policial m\u00e1s cercana.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un robo de importantes materiales de construcci\u00f3n fue denunciado este lunes en la Comisar\u00eda 14. El hecho ocurri\u00f3 en una obra &#8230;<\/p>\n","protected":false},"author":7,"featured_media":144030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[201,4],"tags":[],"class_list":["post-146149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inseguridad","category-policiales"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/146149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=146149"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/146149\/revisions"}],"predecessor-version":[{"id":146150,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/146149\/revisions\/146150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/144030"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=146149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=146149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=146149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}