{"id":145389,"date":"2025-03-15T10:21:03","date_gmt":"2025-03-15T13:21:03","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=145389"},"modified":"2025-03-17T09:51:08","modified_gmt":"2025-03-17T12:51:08","slug":"ladrones-ingresaron-a-una-vivienda-y-sustrajeron-una-consola-de-video-juegos-y-otros-elementos","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/ladrones-ingresaron-a-una-vivienda-y-sustrajeron-una-consola-de-video-juegos-y-otros-elementos\/","title":{"rendered":"LADRONES INGRESARON A UNA VIVIENDA Y SUSTRAJERON UNA CONSOLA DE VIDEO JUEGOS Y OTROS ELEMENTOS"},"content":{"rendered":"<h4 data-sourcepos=\"5:1-5:277\">Un robo tuvo lugar en una vivienda ubicada en la calle Manuel Estrada 587, promediando las 21:30 del d\u00eda viernes. La v\u00edctima, identificada como E. O. M., un hombre de 32 a\u00f1os, denunci\u00f3 el hecho en la Comisar\u00eda 14\u00b0.<\/h4>\n<p data-sourcepos=\"7:1-7:279\">Seg\u00fan el relato de la v\u00edctima, <strong>al regresar a su domicilio, constat\u00f3 que desconocidos hab\u00edan ingresado tras forzar la puerta principal.<\/strong> Los delincuentes <strong>sustrajeron una consola PlayStation 4, cinco juegos de la misma consola, un cable HDMI, un cable de alimentaci\u00f3n y un joystick.<\/strong><\/p>\n<p data-sourcepos=\"9:1-9:114\">La v\u00edctima asegur\u00f3 haber dejado su vivienda con las medidas de seguridad correspondientes al momento de su salida.<\/p>\n<p data-sourcepos=\"11:1-11:203\">Las autoridades policiales se encuentran investigando el caso y han solicitado la intervenci\u00f3n del Ayudante Fiscal, quien dispuso las medidas de rigor para esclarecer el hecho y dar con los responsables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un robo tuvo lugar en una vivienda ubicada en la calle Manuel Estrada 587, promediando las 21:30 del d\u00eda viernes. La &#8230;<\/p>\n","protected":false},"author":7,"featured_media":145390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[201,4],"tags":[],"class_list":["post-145389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inseguridad","category-policiales"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/145389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=145389"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/145389\/revisions"}],"predecessor-version":[{"id":145391,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/145389\/revisions\/145391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/145390"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=145389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=145389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=145389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}