{"id":142527,"date":"2024-12-11T10:04:11","date_gmt":"2024-12-11T13:04:11","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=142527"},"modified":"2024-12-12T10:06:01","modified_gmt":"2024-12-12T13:06:01","slug":"gonzalo-antolin-es-de-san-rafael-y-gano-la-ultima-carrera-del-tn-clase-2-con-su-peugeot-208","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/gonzalo-antolin-es-de-san-rafael-y-gano-la-ultima-carrera-del-tn-clase-2-con-su-peugeot-208\/","title":{"rendered":"GONZALO ANTOL\u00cdN ES DE SAN RAFAEL Y GAN\u00d3 LA \u00daLTIMA CARRERA DEL TN CLASE 2 CON SU PEUGEOT 208"},"content":{"rendered":"<h4><span style=\"color: #000000;\">Antol\u00edn cierra el 2024 a lo grande, con un triunfo en Trelew y logrando el 3\u00b0 puesto en el Campeonato\u00a0<\/span><\/h4>\n<p><span style=\"color: #000000;\">Tras una larga temporada, con 12 fechas y un gran compromiso, el piloto Gonzalo Antol\u00edn logr\u00f3 hacerse con la \u00faltima carrera del Turismo Nacional en Clase 2, en el aut\u00f3dromo \u201cMar y valle\u201d de Chubut.<em><strong> \u201cComenzamos en febrero y terminamos de la mejor manera. Muchas veces nos ha tocada alejarnos de casa, haciendo todo a pulm\u00f3n pero movilizados por la pasi\u00f3n\u201d<\/strong><\/em>, expres\u00f3 <span style=\"color: #000080;\"><strong>Gonzalo Antol\u00edn<\/strong><\/span> en di\u00e1logo con <span style=\"color: #800080;\"><strong>FM VI\u00d1AS.<\/strong><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\">Antol\u00edn corre a bordo de un Peugeot 208, el cual es trabajado por su padre y hermano en San Rafael. As\u00ed mismo, el piloto confes\u00f3 que <strong><em>\u201cel mayor desaf\u00edo que hay que enfrentar es el presupuesto, porque es muy caro poder viajar y competir\u201d<\/em> <\/strong>y declar\u00f3 haber en duda sobre competir en la \u00faltima carrera del Turismo Nacional. <strong><em>\u201cNo se trata de falta de apoyo, porque entiendo que la gente colabora siempre con lo que puede. El problema son los grandes n\u00fameros\u201d<\/em><\/strong>, reflexion\u00f3 Antol\u00edn.<\/span><\/p>\n<h2><span style=\"color: #000000;\">LAS POSICIONES DEL CAMPEONATO TN CLASE 2<\/span><\/h2>\n<p><span style=\"color: #000000;\">Con la disputa del Gran Premio Ciudad de Trelew, quedaron definidas las posiciones finales del Campeonato 2024 de TN Clase 2, cuyo vencedor anual fue Thiago Mart\u00ednez, consagrado el pasado 06 de octubre en el Circuito San Juan Villicum (Albard\u00f3n, San Juan), a bordo del Toyota Etios del equipo Ale Bucci Racing, con motorizaci\u00f3n provista por Rub\u00e9n Guerini.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tras doce competencias, el piloto nativo de R\u00edo Gallegos (Santa Cruz), sum\u00f3 un total de 357,50 puntos, superando por 105 unidades a Bautista Damiani, consagrado Subcampe\u00f3n de la divisional el pasado fin de semana. El protagonista, ganador entre los titulares del #TNenBSAS, utiliz\u00f3 un Toyota Yaris atendido por Alquat Motorsport, cuya motorizaci\u00f3n es responsabilidad de Horacio M\u00e1s.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>El tercer puesto de este certamen correspondi\u00f3 a Gonzalo Antol\u00edn, vencedor el pasado domingo en el Aut\u00f3dromo Mar y Valle (Trelew), a bordo del Peugeot 208 atendido por su propio equipo, sumando 243 puntos<\/strong>. Por su parte, Francisco Coltrinari (239 unidades) y Juan Pablo Pastori (231), completaron las principales ubicaciones del certamen que finaliz\u00f3 el pasado domingo.<\/span><\/p>\n<p><span style=\"color: #000000;\">Entre los debutantes, el mejor ubicado fue el piloto uruguayo Joaqu\u00edn Cafaro, a los mandos de un Toyota Etios atendido por GR Competici\u00f3n, quien finaliz\u00f3 el certamen ocupando el s\u00e9ptimo lugar, sumando 194,50 puntos en el certamen que tuvo un total de 64 pilotos que sumaron, al menos, un punto en esta temporada.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antol\u00edn cierra el 2024 a lo grande, con un triunfo en Trelew y logrando el 3\u00b0 puesto en el Campeonato\u00a0 Tras &#8230;<\/p>\n","protected":false},"author":7,"featured_media":142529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[],"class_list":["post-142527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/142527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=142527"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/142527\/revisions"}],"predecessor-version":[{"id":142528,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/142527\/revisions\/142528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/142529"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=142527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=142527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=142527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}