{"id":130944,"date":"2023-12-23T10:38:14","date_gmt":"2023-12-23T13:38:14","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=130944"},"modified":"2023-12-27T08:27:04","modified_gmt":"2023-12-27T11:27:04","slug":"no-dire-nada-pero-habra-senales-la-frase-tendencia-en-redes-que-irrigacion-tomo-para-su-remozada-campana-verano-sin-muertos-de-calor","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/no-dire-nada-pero-habra-senales-la-frase-tendencia-en-redes-que-irrigacion-tomo-para-su-remozada-campana-verano-sin-muertos-de-calor\/","title":{"rendered":"\u00abNO DIR\u00c9 NADA, PERO HABR\u00c1 SE\u00d1ALES\u00bb, LA FRASE TENDENCIA EN REDES QUE IRRIGACI\u00d3N TOM\u00d3 PARA SU REMOZADA CAMPA\u00d1A \u00abVERANO SIN MUERTOS DE CALOR\u00bb"},"content":{"rendered":"<div class=\"gmail_quote\">\n<div dir=\"ltr\">\n<div><strong>El objetivo es generar conciencia sobre el peligro de ba\u00f1arse en cauces no habilitados para ello. El C\u00f3digo Contravencional de la Provincia, adem\u00e1s, pena a quien lo realice con hasta 5 d\u00edas de arresto y multa.<\/strong><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div>\n<div>Desde esta semana circula en los medios radiales, televisivos y digitales piezas realizadas por el Departamento General de Irrigaci\u00f3n que ponen al aire una nueva temporada de concientizaci\u00f3n de<em><strong> \u201cVerano sin muertos de calor\u201d.<\/strong> <\/em>El objetivo es apuntar\u00a0sobre todo a los j\u00f3venes, informar y evitar que se sumerjan en canales, diques, embalses y r\u00edos.<\/div>\n<div><\/div>\n<div>Se trata de una campa\u00f1a fuerte, que pone en el tapete la frase que habitualmente se usa para referirse al calor y que muchas veces se repite sin darle el valor o la importancia a su significado real.<\/div>\n<div><\/div>\n<div>Y en esta oportunidad, la campa\u00f1a anexa la frase que durante 2023 fue tendencia en redes sociales<b>\u00a0\u00abNo dir\u00e9 nada, pero habr\u00e1 se\u00f1ales\u00bb<\/b>, reformulada para tener connotaci\u00f3n peyorativa:\u00a0<b>\u00abCuando me ba\u00f1e en cauces no dir\u00e9 nada, pero habr\u00e1 noticias&#8230;\u00bb<\/b>\u00a0con la intenci\u00f3n de relacionarla a lo ef\u00edmero que puede ser el instante, en el que al sumergirse en un cauce o espejo de agua, se pierde la conciencia y ocurre una tragedia que tristemente se convierte en noticia. Adem\u00e1s esta\u00a0temporada se agrega tambi\u00e9n el \u00edcono de una mano que emerge.<\/div>\n<\/div>\n<div><b>Ba\u00f1arse en cauces de riego est\u00e1 prohibido.\u00a0<\/b>As\u00ed lo determina la Ley 9099 y el C\u00f3digo\u00a0<b>Contravencional de la Provincia de Mendoza<\/b>, art. 124.<\/div>\n<h2><b>\u00a1Tomemos conciencia!<\/b><\/h2>\n<\/div>\n<\/div>\n<div class=\"gmail_quote\">\n<div dir=\"ltr\">\n<div>\n<div>Las estad\u00edsticas todos los a\u00f1os son duras. Y los datos que aporta temporada tras temporada Defensa Civil de la Provincia indican que el trabajo de concientizar debe ser continuo. En la mayor\u00eda de los casos reportados, se trata de j\u00f3venes que realizan estas pr\u00e1cticas indebidas o bien ni\u00f1os que escapan a la mirada y control de sus padres.<\/div>\n<div><\/div>\n<div>Existen peligros ocultos en las aguas que en la mayor\u00eda de las ocasiones son mortales para las personas, como rocas, que ante el impacto provocan la p\u00e9rdida de conocimiento. Tambi\u00e9n sistemas de compuertas que succionan el agua y pueden provocar la muerte instant\u00e1nea; la baja temperatura del agua que puede ocasionar un shock t\u00e9rmico, o bien, la propia corriente, que en muchos casos es muy veloz, dependiendo la traza y pendiente del canal, arrastra y sumerge al ba\u00f1ista. En un canal con buena pendiente, circulan 2 mil litros de agua por segundo, lo que equivale al impacto de una camioneta.<\/div>\n<h2><b>Avisar al 911<\/b><\/h2>\n<div>Mendoza cuenta con 38 diques y m\u00e1s de 12 mil km de canales (5000 km en la cuenca del r\u00edo Mendoza entre primarios, secundarios y terciarios), de los cuales un alto porcentaje se encuentra en propiedades privadas (fincas), por lo que es necesario que la ciudadan\u00eda en general tome conciencia de los riesgos que implica ba\u00f1arse en los cauces, ya que en la mayor\u00eda de los casos es imposible contar con la ayuda y auxilio inmediato.<\/div>\n<div><\/div>\n<div>Irrigaci\u00f3n trabaja junto al ministerio de Seguridad y tambi\u00e9n Defensa Civil para despejar las m\u00e1rgenes de los r\u00edos. Y a diario recorre canales en puntos neur\u00e1lgicos de toda la Provincia, y en varias oportunidades junto a la Polic\u00eda de Mendoza, por el accionar violento de muchos ba\u00f1istas que se niegan a retirarse. Temporada tras temporada se pide a la poblaci\u00f3n que ante el avistaje de personas incurriendo en la pr\u00e1ctica se de aviso al 911 para que se active el operativo de alerta.<\/div>\n<h2><b>Qu\u00e9 dice el C\u00f3digo Contravencional<\/b><\/h2>\n<div>La Ley 9.099 que establece el nuevo C\u00f3digo Contravencional de Mendoza, sanciona en su art\u00edculo N\u00ba 124 a los que se ba\u00f1en en cauces de agua no autorizados para ese fin. \u201cEl que usare para ba\u00f1arse cauces de agua, canales de riego, represas, diques derivadores, tomas y cualquier obra hidr\u00e1ulica de la Provincia, no autorizado para ello por la autoridad correspondiente, ser\u00e1 sancionado con multa desde doscientas (200) U.F. hasta quinientas (500) U.F. o arresto desde dos (2) d\u00edas hasta cinco (5) d\u00edas, o trabajo comunitario de cinco (5) d\u00edas\u201d, asegura el C\u00f3digo.<em><strong> \u201cSi el que realizare la conducta descripta en el p\u00e1rrafo anterior fuese menor de edad, los padres, tutores o cuidadores de los mismos que hubieren omitido cumplir con el deber de vigilancia, ser\u00e1n sancionados con la misma sanci\u00f3n prevista para el tipo contravencional\u201d.<\/strong><\/em> En tanto que, en el apartado de contravenciones contra el medioambiente y la salud, en su art\u00edculo N\u00ba 138 pena la obstrucci\u00f3n, alteraci\u00f3n o deterioro de los cauces de agua. <em><strong>\u201cEl que mediante cualquier tipo de actividad intentare entorpecer el normal discurrimiento de las aguas por los canales de la red de riego de la Provincia o alterar el curso de las mismas, arrojando objetos, desvi\u00e1ndolas, o deteriorando las obras de toma, los taludes de los canales, las compuertas o cualquier obra hidr\u00e1ulica de conducci\u00f3n de las mismas, o el que arrojare vertidos con compuestos qu\u00edmicos t\u00f3xicos y contaminantes a los cauces de agua, ser\u00e1 sancionado con multa desde un mil (1.000) U.F. hasta tres mil (3.000) U.F. o arresto de diez (10) d\u00edas, imponi\u00e9ndosele adem\u00e1s la obligaci\u00f3n de realizar cursos sobre medio ambiente, a cargo de la Secretar\u00eda de Ambiente o el organismo que en el futuro la reemplazare\u201d<\/strong><\/em>, asegura el C\u00f3digo.<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo es generar conciencia sobre el peligro de ba\u00f1arse en cauces no habilitados para ello. El C\u00f3digo Contravencional de la &#8230;<\/p>\n","protected":false},"author":7,"featured_media":130948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,37],"tags":[],"class_list":["post-130944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-irrigacion"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/130944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=130944"}],"version-history":[{"count":3,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/130944\/revisions"}],"predecessor-version":[{"id":130993,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/130944\/revisions\/130993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/130948"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=130944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=130944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=130944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}