{"id":123590,"date":"2023-06-20T10:02:08","date_gmt":"2023-06-20T13:02:08","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=123590"},"modified":"2023-06-20T10:02:08","modified_gmt":"2023-06-20T13:02:08","slug":"ponen-en-marcha-creditos-para-13-millones-de-monotributistas","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/ponen-en-marcha-creditos-para-13-millones-de-monotributistas\/","title":{"rendered":"PONEN EN MARCHA CR\u00c9DITOS PARA 1,3 MILLONES DE MONOTRIBUTISTAS"},"content":{"rendered":"<p class=\"news-headline__article-summary\"><strong>A trav\u00e9s de la l\u00ednea Cr\u00e9dito Argentino CreAr para microempresas, los monotributistas pueden acceder al financiamiento por hasta $2,2 millones para inversiones<\/strong><\/p>\n<article class=\"article-body article-body--first-paragraph\" data-td-script-src=\"https:\/\/www.sitioandino.com.ar\/td\/modulos\/encuestas\/js\/function-embeds-min-version-1661266695.js\">Los\u00a0<strong>monotributistas<\/strong>\u00a0<strong>pueden acceder al financiamiento por hasta $2,2 millones para inversiones, a trav\u00e9s de la l\u00ednea Cr\u00e9dito Argentino CreAr para microempresas<\/strong>, anunciada por\u00a0<strong>Sergio Massa<\/strong>, junto con el secretario de Industria y Desarrollo Productivo, Jos\u00e9 Ignacio de Mendiguren, inform\u00f3 el\u00a0<strong>Ministerio de Econom\u00eda<\/strong>.<\/p>\n<\/article>\n<article class=\"article-body article-body--second-paragraph\"><strong>El Gobierno Nacional apunta a llegar a 1.300.000 personas para potenciar el perfil emprendedor y promover el crecimiento argentino<\/strong>, dice la informaci\u00f3n oficial.<\/p>\n<p><em><strong>\u00abEsta nueva herramienta refuerza nuestra pol\u00edtica de impulsar a todo el ciclo de la producci\u00f3n, desde el microemprendimiento hasta la pyme y las empresas medianas y grandes<\/strong><\/em>\u00ab, afirm\u00f3 Mendiguren, quien destac\u00f3: <strong><em>\u00abEl ministro Sergio Massa nos pidi\u00f3 sostener el nivel de actividad y empleo mientras se estabilizan las variables macroecon\u00f3micas y esta medida, como todas las que tomamos, va en esa direcci\u00f3n\u00bb.<\/em><\/strong><\/p>\n<p>CreAr para microempresas productivas destina a monotributistas de todo el pa\u00eds hasta $2,2 millones por cr\u00e9dito para financiar la compra de equipamiento, herramientas y otras necesidades productivas.<\/p>\n<p>Los pr\u00e9stamos est\u00e1n dirigidos a todas las categor\u00edas de monotributistas, con excepci\u00f3n de las m\u00e1s altas (I, J, K) y tendr\u00e1n un plazo de 24 meses con tasa fija durante todo el cr\u00e9dito y bonificaci\u00f3n de 40 puntos del Fondo de Garant\u00edas Argentino (FONDEP).<\/p>\n<p>Adem\u00e1s, cuentan con el respaldo del 100% del Fondo de Garant\u00edas Argentino (FOGAR), lo que implica que los pr\u00e9stamos no ser\u00e1n evaluados por las entidades financieras.<\/p>\n<p>Bancos p\u00fablicos y privados de todo el pa\u00eds ya est\u00e1n adhiriendo a la l\u00ednea, que estar\u00e1 disponible en los pr\u00f3ximos d\u00edas, en algunos casos para solicitar de manera online, en las entidades financieras de cada contribuyente.<\/p>\n<p><em><strong>\u00abCr\u00e9dito Argentino (CreAr) es el programa de financiamiento m\u00e1s grande de la historia reciente del pa\u00eds, se puso en marcha a fines del a\u00f1o pasado y ya cuenta con una inversi\u00f3n de 1 bill\u00f3n de pesos\u00bb<\/strong><\/em>, se\u00f1al\u00f3 el Ministerio de Econom\u00eda.<\/p>\n<p>El esquema de financiamiento de CreAr promueve que todo el entramado productivo, desde un microemprendimiento hasta una PyME exportadora, pueda acceder a financiamiento con tasas bonificadas y garant\u00edas del Estado Nacional para mantener el nivel de actividad, potenciar las exportaciones industriales, generar empleo de calidad e impulsar la transformaci\u00f3n de la estructura productiva.<\/p>\n<p>Desde su lanzamiento, CreAr otorg\u00f3 cr\u00e9ditos a PyMEs de todo el pa\u00eds. El 62% se destin\u00f3 a proyectos fuera del AMBA, lo que permite consolidar la federalizaci\u00f3n del cr\u00e9dito. A su vez, el programa impulsa la generaci\u00f3n de empleo y potencia las exportaciones, ya que el 65% de las empresas que recibieron financiamiento aumentaron su planta de empleo y m\u00e1s del 20% export\u00f3 su producci\u00f3n en 2022.<\/p>\n<p>Esta herramienta tambi\u00e9n busca garantizar la inclusi\u00f3n financiera a trav\u00e9s del otorgamiento de garant\u00edas del Estado Nacional. En marzo de este a\u00f1o, el n\u00famero de cr\u00e9ditos aument\u00f3 en t\u00e9rminos reales con respecto a febrero, mientras que el sistema financiero registra una morosidad de solo el 3,5%.<\/p>\n<p>El programa incluye l\u00edneas con bancos p\u00fablicos, como BNA, Banco Argentino de Desarrollo BICE y bancos provinciales, bancos privados, cr\u00e9ditos directos del FONDEP y l\u00edneas especialmente dise\u00f1adas para MiPYMEs, medianas y grandes empresas, sustituci\u00f3n de importaciones, sectores estrat\u00e9gicos, ampliaci\u00f3n de exportaciones, o adquisici\u00f3n de bienes de capital a trav\u00e9s de leasing, entre otras.<\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la l\u00ednea Cr\u00e9dito Argentino CreAr para microempresas, los monotributistas pueden acceder al financiamiento por hasta $2,2 millones para &#8230;<\/p>\n","protected":false},"author":7,"featured_media":123591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-123590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fmvinas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=123590"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123590\/revisions"}],"predecessor-version":[{"id":123593,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123590\/revisions\/123593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/123591"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=123590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=123590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=123590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}