{"id":123292,"date":"2023-06-13T09:41:44","date_gmt":"2023-06-13T12:41:44","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=123292"},"modified":"2023-06-13T09:41:44","modified_gmt":"2023-06-13T12:41:44","slug":"disconformes-con-la-coprosamen-los-ganaderos-del-oeste-pretenden-administrar-sus-propias-vacunas","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/disconformes-con-la-coprosamen-los-ganaderos-del-oeste-pretenden-administrar-sus-propias-vacunas\/","title":{"rendered":"DISCONFORMES CON LA COPROSAMEN, LOS GANADEROS DEL OESTE PRETENDEN ADMINISTRAR SUS PROPIAS VACUNAS"},"content":{"rendered":"<p><strong>La semana pasada representantes de la Sociedad Rural del Oeste Argentino (SRO) que preside Alfredo Vila, se reunieron en Mendoza con la ingeniera Diana Guill\u00e9n, presidenta de Senasa, con la intenci\u00f3n de saber c\u00f3mo transformarse en un ente apto para implementar en Mendoza la vacunaci\u00f3n contra la aftosa y evitar as\u00ed el costo de intermediaci\u00f3n de Coprosamen. <\/strong><\/p>\n<p>En<span style=\"color: #0000ff;\"><strong> F.M VI\u00d1AS<\/strong> <\/span>tomamos contacto con Dami\u00e1n Carb\u00f3, Director de Ganader\u00eda, qui\u00e9n explic\u00f3 los reclamos.<\/p>\n<p><strong><em>\u201cEst\u00e1 dominando la desinformaci\u00f3n, m\u00e1s que anda el desconocimiento\u201d<\/em><\/strong>, se\u00f1al\u00f3 Carb\u00f3 y explic\u00f3<strong><em> \u201cla vacunaci\u00f3n contra la Aftosa es obligatoria en todo el pa\u00eds y en nuestra regi\u00f3n tiene una vacunaci\u00f3n anual obligatoria que es determinada por el SENASA\u201d. <\/em><\/strong><\/p>\n<p>El Servicio Nacional de Sanidad y Calidad Agroalimentaria delega la funci\u00f3n de vacunaci\u00f3n a trav\u00e9s de la Comision Provinciales de Sanidad Animal, conocida como Coprosa. <em><strong>\u201cEn Mendoza tenemos la Fundaci\u00f3n Coprosamen, que tiene las vacunas para aplicar\u00bb<\/strong><\/em>, explic\u00f3 <span style=\"color: #800080;\"><strong>Damian Carb\u00f3<\/strong><\/span>.<\/p>\n<p>En s\u00edntesis, el SENASA delega la vacunaci\u00f3n a trav\u00e9s de la Comisi\u00f3n Provincial de Sanidad Animal (Coprosa), compuesta por representantes de cada departamento. Luego de definir c\u00f3mo se realizar\u00e1 la vacunaci\u00f3n, la Fundaci\u00f3n Coprosamen presenta los costos de aplicaci\u00f3n los cuales son evaluados.<\/p>\n<p><strong>\u00abLa vacuna tiene un costo de 312 pesos, pero a eso le agregan 81 pesos por honorarios veterinarios, 19 pesos para aportar al Cluster y otros 236 pesos destinados a gastos de la Fundaci\u00f3n Coprosamen. En total, en Mendoza, la vacuna nos cuesta 648 pesos, siendo la m\u00e1s cara del pa\u00eds. En San Luis, por ejemplo, pagan por la misma vacuna, 417 pesos\u00bb<\/strong>, hab\u00eda explicado Alfredo Vila Santander, presidente de la Sociedad Rural del Oeste Argentino.<\/p>\n<p><strong>\u201cEn la provincia tenemos un sistema solidario y por eso se hace un precio unificado, por lo cual los departamentos que tienen mayor densidad de producci\u00f3n estar\u00edamos subsidiando a los departamentos con menor densidad. As\u00ed se conforma el precio de la vacuna en Mendoza\u201d<\/strong>, indic\u00f3 Dami\u00e1n Carb\u00f3 y explic\u00f3 que <em><strong>\u201cpor lo tanto es dif\u00edcil hacer una comparaci\u00f3n con provincias como La Pampa o San Luis\u201d.<\/strong><\/em><\/p>\n<p><strong><em>\u201cPor decisi\u00f3n de los productores, a trav\u00e9s de sus representantes, decidieron que junto al pago de la vacuna se haga el aporte al Cluster, eso da la suba de $19 a la vacuna\u201d<\/em><\/strong>, sostuvo el Director de Ganader\u00eda. Este aporte no es algo nuevo ya que ocurre desde hace 8 a\u00f1os.<\/p>\n<h6><span style=\"color: #ff6600;\"><strong>Vallejos, G.<\/strong><\/span><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La semana pasada representantes de la Sociedad Rural del Oeste Argentino (SRO) que preside Alfredo Vila, se reunieron en Mendoza con &#8230;<\/p>\n","protected":false},"author":7,"featured_media":123293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-123292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fmvinas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=123292"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123292\/revisions"}],"predecessor-version":[{"id":123294,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/123292\/revisions\/123294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/123293"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=123292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=123292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=123292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}