{"id":121351,"date":"2023-04-27T09:22:00","date_gmt":"2023-04-27T12:22:00","guid":{"rendered":"https:\/\/vinasfm.com\/noticias\/?p=121351"},"modified":"2023-04-28T09:41:34","modified_gmt":"2023-04-28T12:41:34","slug":"regresa-el-programa-hogar","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/regresa-el-programa-hogar\/","title":{"rendered":"REGRESA EL PROGRAMA HOGAR"},"content":{"rendered":"<p><strong>El Programa Hogar de la Secretar\u00eda de Energ\u00eda, que ayuda a quienes deben comprar garrafas por falta de gas natural en sus hogares, ser\u00e1 reanudado en mayo.<\/strong><\/p>\n<p>El mismo fue suspendido en noviembre del a\u00f1o pasado debido a una intensa revisi\u00f3n sobre irregularidades en los beneficiarios\/as del programa.<\/p>\n<p><em><strong> \u00abEst\u00e1 dedicado a aquellos que no tienen gas natural en su casa, que deben comprar garrafa. El Gobierno Nacional, desde la Secretar\u00eda de Energ\u00eda, ayuda reconoci\u00e9ndole el 80% del valor de una garrafa\u00bb<\/strong><\/em>, explic\u00f3 Mirna Osorio, jefa de la oficina local de ANSES. Es importante aclarar que los titulares de la Asignaci\u00f3n Universal por Hijo, Asignaci\u00f3n por Embarazo, as\u00ed tambi\u00e9n como jubilados y pensionados que ya percib\u00edan el Programa Hogar no deber\u00e1n volver a inscribirse.<\/p>\n<p>En el mes de junio van a empezar a cobrar retroactivo al mes de mayo.<\/p>\n<h2>\u00bfC\u00f3mo inscribirse?<\/h2>\n<p>La inscripci\u00f3n se realiza a trav\u00e9s de MI ANSES, con el CUIT y la Clave de Seguridad Social.<em><strong> \u00abEs muy f\u00e1cil la inscripci\u00f3n y muy r\u00e1pida. Si tienen inconvenientes, por supuesto, pueden asistir a la oficina con un turno y vamos a proceder a la inscripci\u00f3n, adem\u00e1s los ayudaremos durante los recorridos en los barrios\u00bb<\/strong><\/em>, indic\u00f3 Osorio.<\/p>\n<p><em><strong>\u00abEs importante indicar que aquel ciudadano o ciudadana que vive en una zona donde hay gas natural pero que no tiene en su domicilio instalado el gas, deber\u00e1 traer un certificado de la proveedora de este insumo, certificando justamente eso, que en esa casa no se cuenta con gas natural\u00bb<\/strong><\/em>, destac\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Programa Hogar de la Secretar\u00eda de Energ\u00eda, que ayuda a quienes deben comprar garrafas por falta de gas natural en &#8230;<\/p>\n","protected":false},"author":7,"featured_media":121355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-121351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/121351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=121351"}],"version-history":[{"count":3,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/121351\/revisions"}],"predecessor-version":[{"id":121367,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/121351\/revisions\/121367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/121355"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=121351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=121351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=121351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}