{"id":115301,"date":"2022-10-31T00:12:19","date_gmt":"2022-10-31T03:12:19","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=115301"},"modified":"2022-11-01T08:13:36","modified_gmt":"2022-11-01T11:13:36","slug":"concluyo-el-curso-de-operador-socioterapeutico-2022","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/concluyo-el-curso-de-operador-socioterapeutico-2022\/","title":{"rendered":"CONCLUY\u00d3 EL CURSO DE OPERADOR SOCIOTERAP\u00c9UTICO 2022"},"content":{"rendered":"<h4>Con 25 inscriptos, se realiz\u00f3 la \u00faltima clase del Curso de Operador Socioterap\u00e9utico 2022 dictado por el Psic\u00f3logo Social Diego C\u00e1ceres. El curso es una apuesta del Gobierno Municipal y es coordinado por la Asesor\u00eda de Prevenci\u00f3n de Adicciones. El pr\u00f3ximo mes con fecha a confirmar, se llevar\u00e1 a cabo la entrega de certificados<\/h4>\n<p>Asimismo Diego C\u00e1ceres habl\u00f3 acerca del curso: <em><strong>&#8216;Terminamos la quinta edici\u00f3n lastimosamente tendr\u00eda que ser la octava, pero con la pandemia nos impidi\u00f3 continuar, no tenemos el n\u00famero exacto, pero estamos alrededor de 140 operadores que se han formado en estos a\u00f1os y la verdad es numero grande&#8217;<\/strong><\/em><\/p>\n<p>Tambi\u00e9n habl\u00f3 sobre las adicciones en la actualidad: <em><strong>&#8216;Antes dec\u00edamos est\u00e1 a la vuelta de la esquina, pero en la actualidad est\u00e1 dentro de casa est\u00e1 mucho m\u00e1s cerca que antes, esto es vulnerable en todas las clases sociales, atraviesa absolutamente todo, hay conceptos viejos que debemos desaprenderlos&#8217;\u00a0<\/strong><\/em><\/p>\n<p>Del mismo modo agreg\u00f3:<em><strong> &#8216;Hacemos lo que podemos, eso es lo complicado y tr\u00e1gico, tendr\u00edamos que tener herramientas b\u00e1sicas para encarar esta situaci\u00f3n, lo que se juega mucho ac\u00e1 es el estigma y no hemos podido avanzar, todav\u00eda seguimos hablando de forma despectiva para las personas que sufren de esto&#8217;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 25 inscriptos, se realiz\u00f3 la \u00faltima clase del Curso de Operador Socioterap\u00e9utico 2022 dictado por el Psic\u00f3logo Social Diego C\u00e1ceres. &#8230;<\/p>\n","protected":false},"author":7,"featured_media":115302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15],"tags":[],"class_list":["post-115301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-salud"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/115301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=115301"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/115301\/revisions"}],"predecessor-version":[{"id":115311,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/115301\/revisions\/115311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/115302"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=115301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=115301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=115301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}