{"id":114343,"date":"2022-10-10T00:04:28","date_gmt":"2022-10-10T03:04:28","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=114343"},"modified":"2022-10-12T08:39:06","modified_gmt":"2022-10-12T11:39:06","slug":"fin-de-semana-a-puro-futbol-estos-son-los-resultados-que-dejo-la-septima-fecha-del-futbol-alvearense","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/fin-de-semana-a-puro-futbol-estos-son-los-resultados-que-dejo-la-septima-fecha-del-futbol-alvearense\/","title":{"rendered":"FIN DE SEMANA A PURO F\u00daTBOL, ESTOS SON LOS RESULTADOS QUE DEJ\u00d3 LA S\u00c9PTIMA FECHA DEL F\u00daTBOL ALVEARENSE"},"content":{"rendered":"<p>Fin de semana XXL para el f\u00fatbol alvearense, tres d\u00edas a puro f\u00fatbol para completar la septima fecha del torneo local, conoc\u00e9 los resultados<\/p>\n<p>En primer lugar, el Sport Club Pac\u00edfico sello una gran victoria frente a 10 de septiembre, fue 3 a 1, el lobo calienta motores para el Torneo Regional que comenzar\u00e1 la siguiente semana. En el caso de la rama femenina las chicas del Funebrero no se presentaron.<\/p>\n<p>El domingo por la tarde se jugaron tres encuentros en ambas ramas, de visitante y con una gran presentaci\u00f3n Bowen goleo 8 a 0 a Uni\u00f3n de SL. Los azules de Real del Padre consiguieron tres puntos important\u00edsimos para acomodarse entre los cuatro mejores del torneo, fue resultado a favor por 2 a 0 enfrentando a un Col\u00f3n que a\u00fan no puede conseguir puntos en el torneo al igual que la rama femenina ya que perdieron nuevamente en este caso fue por un tanto contra cero.<\/p>\n<p>Siguiendo con los encuentros del domingo, Argentino y Libetad se vieron las caras en el Estadio de los Funebreros, en primer lugar las chicas del Sport Club Argentino golearon nuevamente, fue 7 a 0 para ellas en una nueva victoria consecutiva, en el caso de la rama masculina fue victoria para Argentino por 2 a 0.<\/p>\n<p>La fecha se complet\u00f3 con el triunfo de Andes sobre Ferro por 1 a 0 en la rama masculina, mientras que en la rama femenina los tres puntos quedaron para las del verde, fue goleada por 4 a 0.<\/p>\n<h6><strong>Ludmila Lucero<\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Fin de semana XXL para el f\u00fatbol alvearense, tres d\u00edas a puro f\u00fatbol para completar la septima fecha del torneo local, &#8230;<\/p>\n","protected":false},"author":7,"featured_media":59792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,3],"tags":[],"class_list":["post-114343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-deportes"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=114343"}],"version-history":[{"count":5,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114343\/revisions"}],"predecessor-version":[{"id":114392,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114343\/revisions\/114392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/59792"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=114343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=114343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=114343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}