{"id":114235,"date":"2022-10-06T08:33:34","date_gmt":"2022-10-06T11:33:34","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=114235"},"modified":"2022-10-08T10:31:07","modified_gmt":"2022-10-08T13:31:07","slug":"alvear-se-fortalece-como-destino-turistico-gracias-a-una-nueva-movilidad-cartelelia-y-otras-acciones","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/alvear-se-fortalece-como-destino-turistico-gracias-a-una-nueva-movilidad-cartelelia-y-otras-acciones\/","title":{"rendered":"ALVEAR SE FORTALECE COMO DESTINO TUR\u00cdSTICO GRACIAS A UNA NUEVA MOVILIDAD, CARTELER\u00cdA Y DEM\u00c1S ACCIONES"},"content":{"rendered":"<h4>El Intendente Walther Marcolini junto a la Ministra de Turismo y Cultura de Mendoza Nora Vicario y la Directora de Turismo Fabiana Gonz\u00e1lez, presentaron una nueva movilidad destinada a promover el turismo local. Adem\u00e1s se refirieron a los resultados del estudio de mercado sobre turismo departamental realizado por UNCuyo y al programa de colocaci\u00f3n de nuevos carteles tur\u00edsticos.<\/h4>\n<p>En la Bodega Fara\u00f3n se present\u00f3 esta nueva movilidad destinada a promover el turismo departamental, el Jefe Comunal asegur\u00f3 que este utilitario cero kil\u00f3metro, que fue adquirido mediante fondos municipales, y que ser\u00e1 fundamental para la difusi\u00f3n de los atractivos de General Alvear, como as\u00ed tambi\u00e9n lo ser\u00e1 la colocaci\u00f3n de nuevos carteles tur\u00edsticos: \u201c<strong>Son 50 carteles en v\u00eda p\u00fablica, que pondr\u00e1 en valor cada lugar que tenemos, desde nuestra bodega, hasta sectores privados, emprendimientos tur\u00edsticos, caba\u00f1as y muchos otros lugares. Esta es una inversi\u00f3n realizada en el mes de mayo de 800 mil pesos, destinados a carteler\u00eda. Adem\u00e1s est\u00e1n encaminados los t\u00f3tems de ingreso a la provincia, una inversi\u00f3n superior a los seis millones y medio de pesos, siempre y cuando se realice r\u00e1pido\u201d.<\/strong><\/p>\n<p>El intendente Walther Marcolini resalt\u00f3 el trabajo realizado junto a la UNCuyo para determinar cu\u00e1l es el tipo de cliente tur\u00edstico que elige General Alvear, cu\u00e1les son las fortalezas y debilidades que tiene el departamento en este aspecto:<strong> \u201cEsto tiene que ver con un feedback. Es una buena experiencia y seguiremos trabajando en esta direcci\u00f3n\u201d.<\/strong><\/p>\n<p>Por su parte, la Ministra de Turismo y Cultura de la Provincia, Nora Vicario, destac\u00f3 la estrategia de General Alvear respecto al turismo y a la cultura, ambos como actividades econ\u00f3micas que derraman trabajo genuino: \u201c<strong>Tener como objetivo el desarrollo del turismo, trabajando fuertemente con el sector privado, es una gran estrategia que valoro y aplaudo\u201d<\/strong> indic\u00f3. Vicario asegur\u00f3 que la colocaci\u00f3n de los cincuenta carteles ponen en valor espacios de nuestro departamento que vienen a potenciar la marca Mendoza en todo el pa\u00eds.<\/p>\n<p><strong>\u201cMendoza est\u00e1 siendo protagonista del turismo nacional y es un destino elegido por los turistas brasileros, que es muy apreciado. Es importante trabajar en equipo para fortalecer la marca Mendoza, el turismo y la cultura hacen que nuestra provincia est\u00e9 siempre adelante en este sector\u201d<\/strong> expres\u00f3 la funcionaria provincial.<\/p>\n<p>La Ministra de Turismo aprovech\u00f3 para realizar un balance acerca de la presencia de Mendoza en la FIT 2022: <strong>\u201cEste es uno de los eventos m\u00e1s importantes de Latinoam\u00e9rica, que est\u00e1 abierta al p\u00fablico durante dos d\u00edas y otros dos d\u00edas se trabaja con empresas. El logro durante esta feria fue que en el stand de Mendoza estuvieran reflejados todos los departamentos trabajando por regiones, entonces cada uno tuvo su espacio y su lugar para ofrecer sus productos, hubo prensa especializada. Estos \u00e1mbitos colaboran para que nos encontremos con pares y generar convenios de colaboraci\u00f3n\u201d.<\/strong><\/p>\n<p>La Directora de Turismo de nuestro departamento Fabiana Gonz\u00e1lez manifest\u00f3: <strong>\u201cFue un d\u00eda muy importante para el sector de nuestro departamento, ya que es la primera vez que la Direcci\u00f3n adquiere una movilidad 0KM para promocionar nuestro destino. Pero tambi\u00e9n es importante el estudio realizado para entender el mercado que elige General Alvear, tenemos un gran desaf\u00edo en cuanto a lo planteado por la UNCuyo, agradezco al sector privado, los fondos del PROMOVER que nos permitieron realizar este estudio y tambi\u00e9n acceder a la se\u00f1al\u00e9tica\u201d.<\/strong><\/p>\n<p>Tras la presentaci\u00f3n de esta movilidad se realiz\u00f3 una visita al edificio de Casa Salonia, que actualmente se est\u00e1 remodelando y que en un futuro ser\u00e1 la sede definitiva de la Direcci\u00f3n de Cultura, recuperando de esta manera un espacio hist\u00f3rico para el departamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Intendente Walther Marcolini junto a la Ministra de Turismo y Cultura de Mendoza Nora Vicario y la Directora de Turismo &#8230;<\/p>\n","protected":false},"author":7,"featured_media":114236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,21],"tags":[],"class_list":["post-114235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-turismo-2"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=114235"}],"version-history":[{"count":5,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114235\/revisions"}],"predecessor-version":[{"id":114254,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/114235\/revisions\/114254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/114236"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=114235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=114235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=114235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}