{"id":111667,"date":"2022-08-02T10:01:37","date_gmt":"2022-08-02T13:01:37","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=111667"},"modified":"2022-08-02T10:01:37","modified_gmt":"2022-08-02T13:01:37","slug":"ate-rechazo-la-propuesta-salarial-del-gobierno-y-no-descarta-implementar-mas-medidas-de-fuerza","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/ate-rechazo-la-propuesta-salarial-del-gobierno-y-no-descarta-implementar-mas-medidas-de-fuerza\/","title":{"rendered":"ATE RECHAZ\u00d3 LA PROPUESTA SALARIAL DEL GOBIERNO Y NO DESCARTA IMPLEMENTAR M\u00c1S MEDIDAS DE FUERZA"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong>Este lunes se retomaron las reuniones paritarias entre el Gobierno provincial y los representantes gremiales de los empleados estatales para informarles la nueva propuesta salarial que\u00a0consisti\u00f3 en un incremento sobre el b\u00e1sico como tambi\u00e9n la revisi\u00f3n de un \u00edtem espec\u00edfico del sector y priorizando a los sueldos m\u00e1s bajos. De esta manera, se les ofreci\u00f3 un aumento de 44% de enero a agosto y fue rechazado.<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">Desde el Ejecutivo acercaron dos propuestas formuladas con responsabilidad y con la finalidad de poder cumplirse durante 2022. En ambos casos estaba prevista una cl\u00e1usula de compromiso, donde el Gobierno se compromet\u00eda a reunirse con la representaci\u00f3n gremial durante noviembre de 2022 a fin de revisar el acuerdo.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Alternativa 1<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">1\u00b0. Un incremento sobre la asignaci\u00f3n de clase vigente al 31\/12\/2021, conforme el siguiente cronograma: 12% en agosto 2022, 6% en septiembre de 2022, 6% en octubre de 2022, 6% en noviembre de 2022. Los porcentajes son no acumulables aplicables sobre la base fija de diciembre de 2021.<\/span><\/p>\n<p><span style=\"color: #000000;\">2\u00b0. Un incremento sobre el \u00edtem Paritaria 2022 R\u00e9gimen 15 (\u00cdtem 1414), el que tiene como base de c\u00e1lculo la Asignaci\u00f3n de Clase 13 del R\u00e9gimen 15 &#8211; Ley 5465 modificatorias y complementarias y que reviste el car\u00e1cter de remunerativo no bonificable, conforme al siguiente esquema:<\/span><\/p>\n<p><span style=\"color: #000000;\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/mediamendoza.com\/fotos\/archivo\/10_20221224233.jpg\" \/><\/span><br \/>\n<span style=\"color: #000000;\">3\u00b0. Una modificaci\u00f3n sobre la suma remunerativa no bonificable (\u00cdtem 1408), la que a partir de agosto de 2022 pasar\u00e1 de ser de $7.200 a $10.000.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Alternativa 2<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">1\u00b0. Un incremento sobre la asignaci\u00f3n de clase vigente al 31\/12\/2021, conforme el siguiente cronograma 12% en agosto 2022, 6% en septiembre de 2022, 6% en octubre de 2022, 6% en noviembre de 2022. Los porcentajes son no acumulables aplicables sobre la base fija de diciembre de 2021.<\/span><\/p>\n<p><span style=\"color: #000000;\">2\u00b0. Un incremento sobre el \u00edtem Paritaria 2022 R\u00e9gimen 15 (\u00cdtem 1414), el que tiene como base de c\u00e1lculo la Asignaci\u00f3n de Clase 13 del R\u00e9gimen 15 &#8211; Ley 5465 modificatorias y complementarias y que reviste el car\u00e1cter de remunerativo no bonificable, conforme al siguiente esquema:<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/mediamendoza.com\/fotos\/archivo\/10_20221224251.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes se retomaron las reuniones paritarias entre el Gobierno provincial y los representantes gremiales de los empleados estatales para informarles &#8230;<\/p>\n","protected":false},"author":8,"featured_media":111675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-111667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-destacadas"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/111667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=111667"}],"version-history":[{"count":2,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/111667\/revisions"}],"predecessor-version":[{"id":111678,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/111667\/revisions\/111678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/111675"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=111667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=111667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=111667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}