{"id":104143,"date":"2022-01-04T23:59:13","date_gmt":"2022-01-05T02:59:13","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=104143"},"modified":"2022-01-06T13:08:41","modified_gmt":"2022-01-06T16:08:41","slug":"alumnos-de-la-escuela-de-agricultura-ponen-en-marcha-las-ecolimpiadas-sustentables","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/alumnos-de-la-escuela-de-agricultura-ponen-en-marcha-las-ecolimpiadas-sustentables\/","title":{"rendered":"ALUMNOS DE LA ESCUELA DE AGRICULTURA PONEN EN MARCHA LAS ECOLIMPIADAS SUSTENTABLES"},"content":{"rendered":"<h4><span style=\"color: #000000;\"><strong>Durante la ma\u00f1ana de este lunes, alumnos organizadores de la 57 Olimpiadas de la Escuela de Agricultura junto a estudiantes de la Escuela T\u00e9cnica Jorge Barraquero, personal de la Cooperativa Anul\u00e9n Suyai y de la Direcci\u00f3n de Gesti\u00f3n Ambiental estuvieron en la Plaza Departamental Carlos Mar\u00eda de Alvear realizando una campa\u00f1a de recolecci\u00f3n de latas de aluminio, que luego transformar\u00e1n en medallas.<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">El <strong>Director de Gesti\u00f3n Ambiental Rainero Caterbetti<\/strong> explic\u00f3 que el <strong>Proyecto Ecolimpiadas Sustentables<\/strong> fue ideado por los alumnos de la <strong>Escuela de Agricultura<\/strong> con el objetivo de recolectar materiales reciclables para luego producir las medallas para las <strong>57\u00b0 Olimpiadas<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para llevar adelante el proyecto <strong>Ecolimpiadas Sustentables<\/strong>, los estudiantes cuentan con la colaboraci\u00f3n de la <strong>Cooperativa de Trabajo Anul\u00e9n Suyai<\/strong>, de la <strong>Direcci\u00f3n de Gesti\u00f3n Ambiental<\/strong> y los alumnos de la Escuela Jorge Barraquero, quienes van a ser los encargados de producir las medallas con materiales reciclados.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8216;<strong><em>La Direcci\u00f3n de Gesti\u00f3n Ambiental promueve una econom\u00eda circular, el desarrollo sostenible, recuperar la mayor cantidad de materiales. Este tipo de iniciativas es excelente y m\u00e1s aun viniendo de la mano de los alumnos que van a hacer las 57 olimpiadas<\/em><\/strong>&#8216;, concluy\u00f3 Caterbetti.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por su parte, la <strong>alumna Magal\u00ed Arenas<\/strong> de la Escuela de Agricultura enfatiz\u00f3 que la campa\u00f1a sali\u00f3 del proyecto presentado en el concurso <strong>Emprende U<\/strong>, que organiza la <strong>UNCuyo<\/strong>. &#8216;<strong><em>Ah\u00ed surgi\u00f3 la idea de Ecolimpiadas sustentables, con la campa\u00f1a de recolecci\u00f3n de latas para armar las medallas de premiaci\u00f3n de las pr\u00f3ximas Olimpiadas. Con esta misi\u00f3n estamos en la plaza departamental de Ciudad, ma\u00f1ana estaremos, de 9 a 12h, en Bowen<\/em><\/strong>&#8216;, expres\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es para destacar que los vecinos cuentan con diferentes puntos de recolecci\u00f3n a d\u00f3nde pueden acercar sus latas de aluminio, como Bamboo, La Estancia, P\u00edccolo Bar. Adem\u00e1s, <strong>en las oficinas de la Direcci\u00f3n de Gesti\u00f3n Ambiental, de lunes a viernes, de 7 a 13h<\/strong>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la ma\u00f1ana de este lunes, alumnos organizadores de la 57 Olimpiadas de la Escuela de Agricultura junto a estudiantes de &#8230;<\/p>\n","protected":false},"author":8,"featured_media":104144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,34],"tags":[],"class_list":["post-104143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-medio-ambiente"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/104143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=104143"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/104143\/revisions"}],"predecessor-version":[{"id":104145,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/104143\/revisions\/104145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/104144"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=104143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=104143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=104143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}