{"id":103194,"date":"2021-12-16T00:01:30","date_gmt":"2021-12-16T03:01:30","guid":{"rendered":"http:\/\/vinasfm.com\/noticias\/?p=103194"},"modified":"2021-12-16T12:28:57","modified_gmt":"2021-12-16T15:28:57","slug":"recomendaciones-para-evitar-caer-en-estafas-a-traves-de-facebook","status":"publish","type":"post","link":"https:\/\/vinasfm.com\/noticias\/recomendaciones-para-evitar-caer-en-estafas-a-traves-de-facebook\/","title":{"rendered":"RECOMENDACIONES PARA EVITAR CAER EN ESTAFAS A TRAV\u00c9S DE FACEBOOK"},"content":{"rendered":"<p>Con el fin de evitar estafas a trav\u00e9s de las\u00a0redes sociales,\u00a0el Ministerio de Seguridad brinda una serie de consejos para concientizar a las personas y\u00a0 evitar esta modalidad delictiva.<\/p>\n<p>La estafa consiste en delincuentes que se hacen pasar por compradores o vendedores para pactar, a trav\u00e9s de Facebook, un encuentro con la persona\u00a0 y as\u00ed cometer un delito.<\/p>\n<p>Adem\u00e1s, estos estafadores pueden utilizar enga\u00f1os para solicitar datos de entidades bancarias, como la CBU o clave Token, que es el elemento de seguridad que sirve para confirmar la identidad cuando se realiza una operaci\u00f3n a trav\u00e9s de\u00a0<em>homebanking<\/em>.<\/p>\n<p>Por este motivo,\u00a0la cartera de Seguridad\u00a0advierte que hay que evitar\u00a0pactar compras o ventas de bienes a trav\u00e9s de las redes sociales y no informar datos privados sobre alguna cuenta bancaria.<\/p>\n<p>Tambi\u00e9n\u00a0aconsejan no comprar\u00a0objetos en comercios no autorizados y menos aun si el precio de venta est\u00e1 por debajo de su valor de mercado. Adem\u00e1s, exigir siempre la factura o ticket al realizar una compra.<\/p>\n<p>Por \u00faltimo, el Ministerio de Seguridad cuenta con la l\u00ednea\u00a0\u201cNo compres robado\u201d, la cual es\u00a0an\u00f3nima y est\u00e1 disponible las 24 horas\u00a0para desalentar la compra de objetos robados.\u00a0Se trata del\u00a00800 222 6111,\u00a0que permite realizar denuncias y aportar informaci\u00f3n sobre sitios de venta ilegal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de evitar estafas a trav\u00e9s de las\u00a0redes sociales,\u00a0el Ministerio de Seguridad brinda una serie de consejos para concientizar &#8230;<\/p>\n","protected":false},"author":8,"featured_media":98057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,33],"tags":[],"class_list":["post-103194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-seguridad"],"_links":{"self":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/103194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/comments?post=103194"}],"version-history":[{"count":1,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/103194\/revisions"}],"predecessor-version":[{"id":103195,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/posts\/103194\/revisions\/103195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media\/98057"}],"wp:attachment":[{"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/media?parent=103194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/categories?post=103194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinasfm.com\/noticias\/wp-json\/wp\/v2\/tags?post=103194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}